{"id":10007,"date":"2024-06-17T20:12:00","date_gmt":"2024-06-17T18:12:00","guid":{"rendered":"https:\/\/www.orpheus-magazin.de\/?p=10007"},"modified":"2024-07-01T20:20:22","modified_gmt":"2024-07-01T18:20:22","slug":"wien-the-gospel-according-to-the-other-mary","status":"publish","type":"post","link":"https:\/\/www.orpheus-magazin.de\/de\/2024\/06\/17\/wien-the-gospel-according-to-the-other-mary\/","title":{"rendered":"Das G\u00f6ttliche im Irdischen"},"content":{"rendered":"<p>Pieter Bruegels Gem\u00e4lde \u201eDie Kreuztragung Christi\u201c (1564), das in seiner detailreichen Darstellung der Passionsgeschichte gleichzeitig Menschen, die ihrer gewohnten Arbeit auf dem Held nachgehen, als auch \u00f6ffentliche Hinrichtungen vorf\u00fchrt, dient John Adams als Bezugspunkt f\u00fcr sein theatralisches Oratorium \u201eThe Gospel According to the Other Mary\u201c. Unz\u00e4hlige Geschichten lassen sich in derartigen \u201eWimmelbildern\u201c der Fr\u00fchrenaissance entdecken: \u201eDas G\u00f6ttliche wird mit der \u00d6dnis des Alltags verwoben.\u201c<\/p>\n\n\n\n<p>Mit der \u201eanderen Maria\u201c ist jene sonst nicht genannte Frau gemeint, die \u2013 nach Matth\u00e4us 28, 1 und 2 \u2013 gemeinsam mit Maria Magdalena als erste zum Grabe Jesus ging. Das Oratorium f\u00fchrt diese Maria von Bethanien, die Jesus die F\u00fc\u00dfe wusch, und deren beide Geschwister vor: Martha und ihren kranken Bruder Lazarus, den Jesus von den Toten erweckte. Sie verkehren mit H\u00e4ftlingen, Ausgesto\u00dfenen, politisch Verfolgten, aber auch schr\u00e4gen \u201eParadiesv\u00f6geln\u201c. Meist versammelt man sich am K\u00fcchentisch in einem Wohncontainer, der auch als vollgef\u00fclltes Kleiderlager dient. Martha betreibt hier n\u00e4mlich ein Heim f\u00fcr Obdachlose und arbeitslose Frauen und sammelt f\u00fcr sie Spenden ein. Zu sehen sind im B\u00fchnenbild von Sarah Nixon \u201eTableaux vivants\u201c in magischem Realismus. Wer von den G\u00e4sten dieses Heims der Wunder wirkende Jesus ist, bleibt offen \u2013 einer der drei mitten unter den Obdachlosen stehenden Counterten\u00f6re? Die Figuren bestreiten keine dramatischen Dialoge, sondern berichten und erz\u00e4hlen, vor allem immer wieder sehr eindringlich Wallis Giunta als Maria Magdalena, aber auch die Altistin Jasmin White und der Tenor Alok Kumar als Martha und Lazarus. Eine durchgehende Handlung fehlt, denn Peter Sellars hat neben der Bibel in sein Libretto unterschiedliche Texte von Hildegard von Bingen, Primo Levi, von afroamerikanischen und indigenen Autorinnen oder die Autobiografie der Sozialaktivistin Dorothy Day integriert.<\/p>\n\n\n\n<p>Nach der Pause tritt der 70-k\u00f6pfige Chor in den Vordergrund: Es kommt zu Polizeirazzien, Aufst\u00e4nden und gewerkschaftlichem Widerstand in den Weinbergen. \u201eWer zum Schwerte greift, wird mit dem Schwert umkommen.\u201c Ein abgeschlagenes Ohr tanzt in Lisenka Heijboer Casta\u00f1\u00f3ns Inszenierung surreal zwischen den Aufst\u00e4ndischen und zitiert dabei das Riesenohr aus Hieronymus Bosch Gem\u00e4lde \u201eDer Garten der L\u00fcste\u201c. Dynamik bringen nun vor allem die Balletteins\u00e4tze (Choreografie: Miguel Alejandro Castillo Le Maitre).<\/p>\n\n\n\n<p>John Adams\u2019 Komposition, ein unerm\u00fcdliches Beben und Brausen \u2013 durchsetzt mit Zitaten barocker und fern\u00f6stlicher Musik oder durchbrochen von einem Klarinettensolo \u2013 transzendiert das Geschehen, durchaus spannungsreich vom Volksopernorchester unter Nicole Paiement umgesetzt.<\/p>\n\n\n\n<p>Mag sein, dass es dem allzu un\u00fcbersichtlichen und \u00fcberladenen Werk an Stringenz fehlt. In das politisch aktivistische Konzept der Wiener Festwochen unter Milo Rau, mit denen die Volksoper kooperiert, l\u00e4sst es sich jedoch gut einordnen. Und f\u00fcr ein \u201ePassions-Oratorium\u201c haben Adams und Sellers eine \u00fcberraschende und durchaus konsequente Form gefunden.<\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>Bernhard Doppler<\/em><\/p>\n\n\n\n<p><strong>\u201eThe Gospel According to the Other Mary\u201c (2012) \/\/ Ein Passions-Oratorium von John Adams (Musik) und Peter Sellars (Libretto)<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p><span class=\"location\">Wien \/ Volksoper Wien (Juni 2024)<\/span><\/br><br \/>\nJohn Adams\u2019 Passions-Oratorium \u201eThe Gospel According to the Other Mary\u201c<\/p>","protected":false},"author":12,"featured_media":10009,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"tpgb_global_settings":"","_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_eb_attr":"","footnotes":""},"categories":[34,1700],"tags":[],"class_list":["post-10007","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rezensionen","category-rezensionen-2024-04"],"tpgb_featured_images":{"full":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2024\/07\/Volksoper-Wien_The-Gospel-According-to-the-Other-Mary-c-Barbara-Palffy-Volksoper-Wien.png",1500,844,false],"tp-image-grid":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2024\/07\/Volksoper-Wien_The-Gospel-According-to-the-Other-Mary-c-Barbara-Palffy-Volksoper-Wien.png",700,394,false],"thumbnail":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2024\/07\/Volksoper-Wien_The-Gospel-According-to-the-Other-Mary-c-Barbara-Palffy-Volksoper-Wien-150x150.png",150,150,true],"medium":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2024\/07\/Volksoper-Wien_The-Gospel-According-to-the-Other-Mary-c-Barbara-Palffy-Volksoper-Wien-300x169.png",300,169,true],"medium_large":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2024\/07\/Volksoper-Wien_The-Gospel-According-to-the-Other-Mary-c-Barbara-Palffy-Volksoper-Wien-768x432.png",600,338,true],"large":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2024\/07\/Volksoper-Wien_The-Gospel-According-to-the-Other-Mary-c-Barbara-Palffy-Volksoper-Wien-1024x576.png",600,338,true],"default":"https:\/\/www.orpheus-magazin.de\/wp-content\/plugins\/the-plus-addons-for-block-editor\/assets\/images\/tpgb-placeholder.jpg"},"tpgb_post_meta_info":{"get_date":"17. Juni 2024","get_modified_date":"1. Juli 2024","category_list":{"category":[{"term_id":34,"name":"Rezensionen","slug":"rezensionen","term_group":0,"term_taxonomy_id":34,"taxonomy":"category","description":"","parent":0,"count":507,"filter":"raw","order":"0"},{"term_id":1700,"name":"Rezensionen 2024\/04","slug":"rezensionen-2024-04","term_group":0,"term_taxonomy_id":1700,"taxonomy":"category","description":"","parent":34,"count":9,"filter":"raw","order":"0"}],"post_tag":false},"author_name":"Florian Maier","author_url":"https:\/\/www.orpheus-magazin.de\/de\/author\/redaktionorpheus-magazin-de\/","author_email":"redaktion@orpheus-magazin.de","author_website":"","author_description":"","author_facebook":"","author_twitter":"","author_instagram":"","author_role":["administrator"],"author_firstname":"Florian","author_lastname":"Maier","user_login":"redaktion@orpheus-magazin.de","author_avatar":"<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/5ee5bbfa3e4d8e8fd4c1781cc619164177d374083eb6aa532bc9f2ba5f9c346a?s=200&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/5ee5bbfa3e4d8e8fd4c1781cc619164177d374083eb6aa532bc9f2ba5f9c346a?s=400&#038;d=mm&#038;r=g 2x' class='avatar avatar-200 photo' height='200' width='200' decoding='async'\/>","author_avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5ee5bbfa3e4d8e8fd4c1781cc619164177d374083eb6aa532bc9f2ba5f9c346a?s=96&d=mm&r=g","comment_count":0,"post_likes":0,"post_views":0},"tpgb_post_category":{"category":"<a href=\"https:\/\/www.orpheus-magazin.de\/de\/category\/rezensionen\/\" alt=\"Rezensionen\"  class=\"category-rezensionen\">Rezensionen<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/category\/rezensionen\/rezensionen-2024-04\/\" alt=\"Rezensionen 2024\/04\"  class=\"category-rezensionen-2024-04\">Rezensionen 2024\/04<\/a> "},"_links":{"self":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/posts\/10007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/comments?post=10007"}],"version-history":[{"count":0,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/posts\/10007\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/media\/10009"}],"wp:attachment":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/media?parent=10007"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/categories?post=10007"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/tags?post=10007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}