{"id":10168,"date":"2024-10-05T15:05:12","date_gmt":"2024-10-05T13:05:12","guid":{"rendered":"https:\/\/www.orpheus-magazin.de\/?p=10168"},"modified":"2024-10-17T21:13:01","modified_gmt":"2024-10-17T19:13:01","slug":"lyon-wozzeck","status":"publish","type":"post","link":"https:\/\/www.orpheus-magazin.de\/de\/2024\/10\/05\/lyon-wozzeck\/","title":{"rendered":"Versuchskaninchen"},"content":{"rendered":"<p>Ein Geruch h\u00e4ngt \u00fcber der B\u00fchne. Ein Geruch von Armut, Treibjagd, Ausweglosigkeit und Unheil. Franz hei\u00dft der Mensch, das Tier, das Opfer. Unterwegs mit Plastikt\u00fcte, stets gehetzt, wird er erst zum M\u00f6rder, bevor er Hand an sich selbst legt. Dabei wollte er unbedingt \u2019raus der Misere seiner kleinen ungeordneten Familie, indem er sich und seinen Leib der wissenschaftlichen Medizin verkaufte. Um diese Dienstleistung spezieller Art k\u00e4mpft er in seiner Not auch gegen die Menschenmaterial-Konkurrenz.<\/p>\n\n\n\n<p>Doch hier, im sinnf\u00e4llig schwarzen Opernhaus von Lyon, hat er nach Georg B\u00fcchner nicht nur den privaten Interessen eines ehrgeizigen Doktors Folge zu leisten, hier ist er ausgew\u00e4hlter Proband eines weit gr\u00f6\u00dferen Menschenexperiments, von dem Medizin, Milit\u00e4r, Kirche und Staat zu profitieren suchen. Etwas unscharf in der Anordnung formuliert: Zu was ist der Mensch f\u00e4hig? Zu was ist er in der Lage, wird er nur hinreichend drangsaliert? Ein Suchscheinwerfer beleuchtet es konstant.<\/p>\n\n\n\n<p>Nicht Bohnen-Di\u00e4t, nicht Sch\u00f6psenfleisch-Di\u00e4t, nicht, dass es ihm verboten ist, \u00f6ffentlich zu husten, wird Franz zur gr\u00f6\u00dften Qual \u2013 und auch nicht, dass er seine diagnostizierten geistigen Verirrungen pflegen soll \u2013, sondern dieser stattliche Tambourmajor, der so ungeheuren Eindruck macht auf Marie, Franzens Lebensgef\u00e4hrtin. Dieser Tambourmajor ist eingeweiht und Instrument des Forschungsvorhabens; er installiert in Maries enger, billiger Wohnk\u00fcche eine \u00dcberwachungskamera, die Live-Bilder zu senden hat ins wissenschaftliche Zentrum, wo der Doktor, der Hauptmann, ein Pastor sowie ein Minister den Lauf ihrer Untersuchungen verfolgen. Zwei Momente gibt\u2019s, die die Studie arg forcieren: wenn sich der Tambourmajor in der engen Schlafkammer hinter der K\u00fcche Marie gef\u00fcgig macht und Franz von Doktor und Hauptmann dieser Beischlaf gesteckt wird. Nun kennt Wozzeck kein Halten mehr: Marie wird zum Kollateralschaden des Experiments \u2013 und wenig sp\u00e4ter dann ersticht der Proband sich selbst.<\/p>\n\n\n\n<p>Kirche, Milit\u00e4r, Politik aber: Sie wenden sich kopfsch\u00fcttelnd ab, zeigen sich emp\u00f6rt \u00fcber den \u201eWissensdrang\u201c der Medizin. Was bleibt nach Richard Brunels drastischer, fatalistischer, soghafter, gro\u00dfst\u00e4dtischer und naturferner Inszenierung von starker Personenf\u00fchrung? Es bleibt das gemeinsame Kind von Marie und Franz, das medienabgelenkt nicht so recht begreift, was der Tod seiner Eltern ihm bedeuten wird.<\/p>\n\n\n\n<p>Der Lyoner Intendant kochte selbst, und auch die musikalische Leitung bleibt Chefsache: Daniele Rustioni dirigiert einen zugespitzten, gesch\u00e4rften, dramatisch packenden Berg-\u201eWozzeck\u201c \u2013 Szene und Graben gehen Hand in Hand. Und St\u00e9phane Degout singt und spielt die Titelrolle ungew\u00f6hnlich wehrhaft-k\u00e4mpferisch, freilich librettogem\u00e4\u00df erfolglos, w\u00e4hrend Ambur Braid als Marie und Pragmatikerin des Lebens sich ungew\u00f6hnlich schn\u00f6rkellos und volumin\u00f6s ent\u00e4u\u00dfert. Vorz\u00fcglich daneben: der hohe Tenor von Thomas Ebenstein als Hauptmann.<\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>R\u00fcdiger Heinze<\/em><\/p>\n\n\n\n<p><strong>\u201eWozzeck\u201c (1925) \/\/ Oper von Alban Berg<\/strong><\/p>\n\n\n\n<p><a href=\"https:\/\/www.opera-lyon.com\/en\/programme\/saison-2024-2025\/opera\/wozzeck-1\" target=\"_blank\" rel=\"noreferrer noopener\">Infos und Termine auf der Website der Op\u00e9ra de Lyon<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p><span class=\"location\">Lyon \/ Op\u00e9ra de Lyon (Oktober 2024)<\/span><\/br> Alban Bergs \u201eWozzeck\u201c als Proband von Medizin, Milit\u00e4r, Kirche und Politik<\/p>","protected":false},"author":12,"featured_media":10169,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"tpgb_global_settings":"","_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_eb_attr":"","footnotes":""},"categories":[34,1705],"tags":[],"class_list":["post-10168","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rezensionen","category-rezensionen-2024-06"],"tpgb_featured_images":{"full":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2024\/10\/Opera-de-Lyon_Wozzeck-c-Jean-Louis-Fernandez.jpg",1500,844,false],"tp-image-grid":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2024\/10\/Opera-de-Lyon_Wozzeck-c-Jean-Louis-Fernandez.jpg",700,394,false],"thumbnail":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2024\/10\/Opera-de-Lyon_Wozzeck-c-Jean-Louis-Fernandez-150x150.jpg",150,150,true],"medium":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2024\/10\/Opera-de-Lyon_Wozzeck-c-Jean-Louis-Fernandez-300x169.jpg",300,169,true],"medium_large":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2024\/10\/Opera-de-Lyon_Wozzeck-c-Jean-Louis-Fernandez-768x432.jpg",600,338,true],"large":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2024\/10\/Opera-de-Lyon_Wozzeck-c-Jean-Louis-Fernandez-1024x576.jpg",600,338,true],"default":"https:\/\/www.orpheus-magazin.de\/wp-content\/plugins\/the-plus-addons-for-block-editor\/assets\/images\/tpgb-placeholder.jpg"},"tpgb_post_meta_info":{"get_date":"5. Oktober 2024","get_modified_date":"17. Oktober 2024","category_list":{"category":[{"term_id":34,"name":"Rezensionen","slug":"rezensionen","term_group":0,"term_taxonomy_id":34,"taxonomy":"category","description":"","parent":0,"count":507,"filter":"raw","order":"0"},{"term_id":1705,"name":"Rezensionen 2024\/06","slug":"rezensionen-2024-06","term_group":0,"term_taxonomy_id":1705,"taxonomy":"category","description":"","parent":34,"count":6,"filter":"raw","order":"0"}],"post_tag":false},"author_name":"Florian Maier","author_url":"https:\/\/www.orpheus-magazin.de\/de\/author\/redaktionorpheus-magazin-de\/","author_email":"redaktion@orpheus-magazin.de","author_website":"","author_description":"","author_facebook":"","author_twitter":"","author_instagram":"","author_role":["administrator"],"author_firstname":"Florian","author_lastname":"Maier","user_login":"redaktion@orpheus-magazin.de","author_avatar":"<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/5ee5bbfa3e4d8e8fd4c1781cc619164177d374083eb6aa532bc9f2ba5f9c346a?s=200&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/5ee5bbfa3e4d8e8fd4c1781cc619164177d374083eb6aa532bc9f2ba5f9c346a?s=400&#038;d=mm&#038;r=g 2x' class='avatar avatar-200 photo' height='200' width='200' decoding='async'\/>","author_avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5ee5bbfa3e4d8e8fd4c1781cc619164177d374083eb6aa532bc9f2ba5f9c346a?s=96&d=mm&r=g","comment_count":0,"post_likes":0,"post_views":0},"tpgb_post_category":{"category":"<a href=\"https:\/\/www.orpheus-magazin.de\/de\/category\/rezensionen\/\" alt=\"Rezensionen\"  class=\"category-rezensionen\">Rezensionen<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/category\/rezensionen\/rezensionen-2024-06\/\" alt=\"Rezensionen 2024\/06\"  class=\"category-rezensionen-2024-06\">Rezensionen 2024\/06<\/a> "},"_links":{"self":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/posts\/10168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/comments?post=10168"}],"version-history":[{"count":0,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/posts\/10168\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/media\/10169"}],"wp:attachment":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/media?parent=10168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/categories?post=10168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/tags?post=10168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}