{"id":10566,"date":"2025-03-18T19:26:49","date_gmt":"2025-03-18T18:26:49","guid":{"rendered":"https:\/\/www.orpheus-magazin.de\/?p=10566"},"modified":"2025-04-27T19:40:26","modified_gmt":"2025-04-27T17:40:26","slug":"hamburg-maria-stuarda","status":"publish","type":"post","link":"https:\/\/www.orpheus-magazin.de\/de\/2025\/03\/18\/hamburg-maria-stuarda\/","title":{"rendered":"Zerfasert"},"content":{"rendered":"<p>Im Zentrum von Donizettis Belcanto-Oper \u201eMaria Stuarda\u201c steht der Streit der beiden K\u00f6niginnen Elisabeth I. und Maria Stuart um Macht und Liebe. Beide begehren den Grafen Leicester, woraus ein Sog an Eifersucht entsteht, der sich beim Aufeinandertreffen entl\u00e4dt.<\/p>\n\n\n\n<p>Karin Beier setzt in der allerersten Inszenierung dieses Werks an der Staatsoper Hamburg vor der Musik auf das Wort: Statt die Ouvert\u00fcre erklingen zu lassen, tritt ein Elisabetta-Double auf und spricht einen Prolog. Selbiges wiederholt sich mit einem Maria-Double im zweiten Akt. Gerne w\u00fcrde man diesem Regie-Einfall etwas abgewinnen, die Monologe bieten aber keinen inhaltlichen Mehrwert, nehmen dem Musiktheater allerdings Wirkung. Neben Maria und Elisabetta befinden sich je bis zu f\u00fcnf Doubles auf der B\u00fchne, mit denen Beier die Innenwelten der K\u00f6niginnen in unterschiedlichen Facetten nach au\u00dfen kehrt, die Hauptdarstellerinnen selbst aber mitunter blass wirken l\u00e4sst.<\/p>\n\n\n\n<p>Wenn Elisabetta sich von Maria verfolgt f\u00fchlt, \u00fcberzeugen die Doubles \u2013 sie ist pl\u00f6tzlich \u00fcberall. Dass die echte Maria mehr das Publikum als Elisabetta anfleht, obwohl sie neben dieser kniet, l\u00e4sst viel Intensit\u00e4t auf der Strecke. Auch der Streit um Leicester verliert sich etwas. Insgesamt wird das Ringen der K\u00f6niginnen nicht schl\u00fcssig dargestellt, wodurch der Kern der Oper zerfasert. Das Ende misslingt g\u00e4nzlich: Scheinwerfer werden heruntergelassen, zwei Kameraleute kommen auf die B\u00fchne, und w\u00e4hrend man noch r\u00e4tselt, was das alles soll (eine Anspielung auf Reality-TV-Shows?), legt Maria sich auf einen Schreibtisch, und der Schlussakkord erklingt. All das wirkt so unfertig, dass nur zu hoffen bleibt, dass die der Premiere vorausgegangenen Streiks die Erkl\u00e4rung daf\u00fcr sind.<\/p>\n\n\n\n<p>Die trist-graue B\u00fchne von Amber Vandenhoeck, in Gef\u00e4ngnis-Optik beleuchtet von Neonr\u00f6hren, und die gro\u00dffl\u00e4chigen d\u00fcsteren Videoprojektionen von Severin Renke sorgen f\u00fcr starke Bilder. Besonders intensiv: Maria vorne mit Glatze und eine \u00e4sthetisierte Rasier-Szene als Video. Die Kost\u00fcme von Eva Dessecker setzen historisierende Akzente bei Elisabetta und Maria, der Rest ist neutral modern in Schwarz gehalten, wovon sich der gl\u00e4nzend rote Lack-Mantel Elisabettas abhebt und Assoziationen zu Macht und Fetisch ausl\u00f6st.<\/p>\n\n\n\n<p>Barno Ismatullaeva beeindruckt als perfekte Elisabetta mit durchschlagender und kalter Klarheit, die sie mit einer nahezu be\u00e4ngstigenden Leichtigkeit abliefert. Ermonela Jaho gibt die Stuarda anf\u00e4nglich zart und zur\u00fcckhaltend, selbst in schwindelerregenden H\u00f6hen \u2013 singt sich aber auch volumin\u00f6s in Rage, wovon man sich mehr w\u00fcnscht. Long Long kann mit seiner vollen, emotional timbrierten Stimme als Leicester \u00fcberzeugen, ist jedoch zu weinerlich. Musikalisch fallen vor allem das beschwingte Dirigat von Antonino Fogliani auf und der heimliche Star des Abends: Chorleiter Eberhard Friedrich, der sich mit dieser Produktion in den Ruhestand verabschiedet, nicht ohne einen beeindruckenden Klangk\u00f6rper zu hinterlassen \u2013 himmlisch sch\u00f6n das \u201eDeh! Tu di un\u2019umile preghiera\u201c.<\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>Christoph Oscar Hofbauer<\/em><\/p>\n\n\n\n<p><strong>\u201eMaria Stuarda\u201c (1834\/35) \/\/ Tragedia lirica von Gaetano Donizetti<\/strong><\/p>\n\n\n\n<p><a href=\"https:\/\/www.staatsoper-hamburg.de\/de\/spielplan\/stueck.php?AuffNr=221618\" target=\"_blank\" rel=\"noreferrer noopener\">Infos und Termine auf der Website der Staatsoper Hamburg<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p><span class=\"location\">Hamburg \/ Staatsoper Hamburg (M\u00e4rz 2025)<\/span><\/br> Viele Doubles f\u00fcr Donizettis \u201eMaria Stuarda\u201c <\/p>","protected":false},"author":12,"featured_media":10567,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"tpgb_global_settings":"","_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_eb_attr":"","footnotes":""},"categories":[34,1811],"tags":[],"class_list":["post-10566","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rezensionen","category-rezensionen-2025-03"],"tpgb_featured_images":{"full":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2025\/04\/Staatsoper-Hamburg_Maria_Stuarda-c-Brinkhoff-Moegenburg.jpg",1500,844,false],"tp-image-grid":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2025\/04\/Staatsoper-Hamburg_Maria_Stuarda-c-Brinkhoff-Moegenburg.jpg",700,394,false],"thumbnail":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2025\/04\/Staatsoper-Hamburg_Maria_Stuarda-c-Brinkhoff-Moegenburg-150x150.jpg",150,150,true],"medium":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2025\/04\/Staatsoper-Hamburg_Maria_Stuarda-c-Brinkhoff-Moegenburg-300x169.jpg",300,169,true],"medium_large":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2025\/04\/Staatsoper-Hamburg_Maria_Stuarda-c-Brinkhoff-Moegenburg-768x432.jpg",600,338,true],"large":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2025\/04\/Staatsoper-Hamburg_Maria_Stuarda-c-Brinkhoff-Moegenburg-1024x576.jpg",600,338,true],"default":"https:\/\/www.orpheus-magazin.de\/wp-content\/plugins\/the-plus-addons-for-block-editor\/assets\/images\/tpgb-placeholder.jpg"},"tpgb_post_meta_info":{"get_date":"18. M\u00e4rz 2025","get_modified_date":"27. April 2025","category_list":{"category":[{"term_id":34,"name":"Rezensionen","slug":"rezensionen","term_group":0,"term_taxonomy_id":34,"taxonomy":"category","description":"","parent":0,"count":507,"filter":"raw","order":"0"},{"term_id":1811,"name":"Rezensionen 2025\/03","slug":"rezensionen-2025-03","term_group":0,"term_taxonomy_id":1811,"taxonomy":"category","description":"","parent":34,"count":12,"filter":"raw","order":"0"}],"post_tag":false},"author_name":"Florian Maier","author_url":"https:\/\/www.orpheus-magazin.de\/de\/author\/redaktionorpheus-magazin-de\/","author_email":"redaktion@orpheus-magazin.de","author_website":"","author_description":"","author_facebook":"","author_twitter":"","author_instagram":"","author_role":["administrator"],"author_firstname":"Florian","author_lastname":"Maier","user_login":"redaktion@orpheus-magazin.de","author_avatar":"<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/5ee5bbfa3e4d8e8fd4c1781cc619164177d374083eb6aa532bc9f2ba5f9c346a?s=200&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/5ee5bbfa3e4d8e8fd4c1781cc619164177d374083eb6aa532bc9f2ba5f9c346a?s=400&#038;d=mm&#038;r=g 2x' class='avatar avatar-200 photo' height='200' width='200' decoding='async'\/>","author_avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5ee5bbfa3e4d8e8fd4c1781cc619164177d374083eb6aa532bc9f2ba5f9c346a?s=96&d=mm&r=g","comment_count":0,"post_likes":0,"post_views":0},"tpgb_post_category":{"category":"<a href=\"https:\/\/www.orpheus-magazin.de\/de\/category\/rezensionen\/\" alt=\"Rezensionen\"  class=\"category-rezensionen\">Rezensionen<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/category\/rezensionen\/rezensionen-2025-03\/\" alt=\"Rezensionen 2025\/03\"  class=\"category-rezensionen-2025-03\">Rezensionen 2025\/03<\/a> "},"_links":{"self":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/posts\/10566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/comments?post=10566"}],"version-history":[{"count":0,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/posts\/10566\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/media\/10567"}],"wp:attachment":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/media?parent=10566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/categories?post=10566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/tags?post=10566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}