{"id":10586,"date":"2025-03-05T16:15:58","date_gmt":"2025-03-05T15:15:58","guid":{"rendered":"https:\/\/www.orpheus-magazin.de\/?p=10586"},"modified":"2025-04-28T16:26:16","modified_gmt":"2025-04-28T14:26:16","slug":"wien-norma","status":"publish","type":"post","link":"https:\/\/www.orpheus-magazin.de\/de\/2025\/03\/05\/wien-norma\/","title":{"rendered":"Waldmenschen im Stehtheater"},"content":{"rendered":"<p>Seit 28 Jahren war in Wien keine szenische \u201eNorma\u201c mehr zu sehen, und nun erlebt man zwei Neuproduktionen innerhalb einer Woche. Die Abstimmungsprobleme der Wiener Opernh\u00e4user haben den Vorteil, dass bei pl\u00f6tzlicher Erkrankung von Juan Diego Fl\u00f3rez ein anderer, eingesungener Pollione in der Stadt weilt. W\u00e4hrend Fl\u00f3rez in der Generalprobe den liebenden, z\u00e4rtlichen Verf\u00fchrer von unschuldigen Priesterinnen ausgezeichnet mimt und mit stimmlicher Sch\u00f6nheit aufwartet, gibt sich Einspringer Freddie De Tommaso eher als arroganter, grober Machtmensch mit Hitlerb\u00e4rtchen, der wie ein Schl\u00e4chter ein Unschuldslamm zur Schlachtbank (ent)f\u00fchren will. Diese Pollione-Charakterisierung wird von der Produktion des MusikTheaters an der Wien \u00fcbernommen und passt dort besser zum Gesamtkonzept. Zwar verf\u00fcgt De Tommaso \u00fcber die n\u00f6tige Stimmkraft und Dynamik, jedoch nicht \u00fcber sch\u00f6n-geschwungene Legato-Linien, Geschmeidigkeit und strahlende H\u00f6he. Ideale S\u00e4nger f\u00fcr diese Rolle sind beide Ten\u00f6re nicht.<\/p>\n\n\n\n<p>Federica Lombardi ist als gro\u00dfe Mozart-Interpretin mit lyrischem Sopran bekannt und zeigt bei ihrem Rollendeb\u00fct eine w\u00fcrdevolle Oberpriesterin, leidende Frau und liebende Mutter. Ihre Rachegel\u00fcste wirken weniger glaubw\u00fcrdig als ihr Wunsch nach Liebe und Frieden, dramatische Steigerungen fehlen leider. Mit technischer Bravour, sch\u00f6nem Legato und weitgespannten Kantilenen meistert sie die anspruchsvolle Partie, sollte aber noch viel mehr ber\u00fchren \u2013 wie beim innigen Gebet an die Mondg\u00f6ttin oder bei ihrer Schlussarie. Auch der eine oder andere Spitzenton gelingt nicht glasklar. Die herrliche H\u00f6he sticht bei Vasilisa Berzhanskaya als gehemmte Adalgisa heraus \u2013 ebenso ihre gehaltvollen tiefen Lagen, gro\u00dfe stimmliche Agilit\u00e4t und eine umfassende Stimmgewalt. Man fragt sich, ob hier nicht eine zuk\u00fcnftige Norma zu erleben ist. Mit kr\u00e4ftigem, noblem Wohlklang-Bass verleiht Ildebrando D\u2019Arcangelo dem greisen Vater Oroveso passendes Profil.<\/p>\n\n\n\n<p>Michele Mariotti f\u00fchrt die Wiener Philharmoniker mit spielerischer Brillanz und kantabler Intensit\u00e4t in die geheimnisvolle Druiden-Welt. Besonders die charakteristische Einleitung am Anfang des zweiten Aktes erzeugt herrliche farbenreiche Klangsch\u00f6nheit und vermittelt eine beklemmende Stimmung, als Norma ihre Kinder t\u00f6ten will. Mit sensationeller Leistung beeindruckt auch der Chor, der den Schlusston von \u201eCasta diva\u201c langgezogen hinwegschweben l\u00e4sst.<\/p>\n\n\n\n<p>Die Inszenierung von Cyril Teste zeigt die Druiden gekleidet wie Soldaten der R\u00e9sistance, die sich als Gefangene ihrer Stadt verteidigen m\u00fcssen; angesiedelt in einer Fabrikhalle, die auch als Lazarett dient. Umbauten gelingen ohne st\u00f6rende Pausen, wenn wenige Mauerteile einen Tempel stimmig darstellen oder das Esszimmer von Norma gezeigt wird. Allgegenw\u00e4rtig ist der Wald als Projektion, wo mit Farben verschiedene Stimmungen erzeugt werden. Die Figuren sind offensichtlich Waldmenschen mit einem Fetisch f\u00fcr farbenreiche T\u00fccher, die in religi\u00f6s-rituelle Choreografien \u2013 etwas linkisch \u2013 eingebaut werden. Leider fehlt jegliche Personenf\u00fchrung, meist wird statisch gestanden und die Beziehungen zwischen den Protagonisten kommen darstellerisch nicht zum Ausdruck. Da hilft auch kein Live-Video mit ber\u00fchrenden Projektionen der Gesichter auf dem durchsichtigen Vorhang.<\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>Susanne Lukas<\/em><\/p>\n\n\n\n<p><strong>\u201eNorma\u201c (1831) \/\/ Tragedia lirica von Vincenzo Bellini<\/strong><\/p>\n\n\n\n<p><a href=\"https:\/\/www.wiener-staatsoper.at\/kalender\/detail\/norma\/\" target=\"_blank\" rel=\"noreferrer noopener\">Infos und Termine auf der Website der Wiener Staatsoper<\/a><\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p><span class=\"location\">Wien \/ Wiener Staatsoper (M\u00e4rz 2025)<\/span><\/br> Bellinis \u201eNorma\u201c ohne Spannung und gro\u00dfe Emotionen <\/p>","protected":false},"author":12,"featured_media":10587,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"tpgb_global_settings":"","_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_eb_attr":"","footnotes":""},"categories":[34,1811],"tags":[],"class_list":["post-10586","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rezensionen","category-rezensionen-2025-03"],"tpgb_featured_images":{"full":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2025\/04\/Wiener-Staatsoper_Norma-c-Wiener-Staatsoper-Michael-Poehn.jpg",1500,844,false],"tp-image-grid":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2025\/04\/Wiener-Staatsoper_Norma-c-Wiener-Staatsoper-Michael-Poehn.jpg",700,394,false],"thumbnail":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2025\/04\/Wiener-Staatsoper_Norma-c-Wiener-Staatsoper-Michael-Poehn-150x150.jpg",150,150,true],"medium":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2025\/04\/Wiener-Staatsoper_Norma-c-Wiener-Staatsoper-Michael-Poehn-300x169.jpg",300,169,true],"medium_large":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2025\/04\/Wiener-Staatsoper_Norma-c-Wiener-Staatsoper-Michael-Poehn-768x432.jpg",600,338,true],"large":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2025\/04\/Wiener-Staatsoper_Norma-c-Wiener-Staatsoper-Michael-Poehn-1024x576.jpg",600,338,true],"default":"https:\/\/www.orpheus-magazin.de\/wp-content\/plugins\/the-plus-addons-for-block-editor\/assets\/images\/tpgb-placeholder.jpg"},"tpgb_post_meta_info":{"get_date":"5. M\u00e4rz 2025","get_modified_date":"28. April 2025","category_list":{"category":[{"term_id":34,"name":"Rezensionen","slug":"rezensionen","term_group":0,"term_taxonomy_id":34,"taxonomy":"category","description":"","parent":0,"count":507,"filter":"raw","order":"0"},{"term_id":1811,"name":"Rezensionen 2025\/03","slug":"rezensionen-2025-03","term_group":0,"term_taxonomy_id":1811,"taxonomy":"category","description":"","parent":34,"count":12,"filter":"raw","order":"0"}],"post_tag":false},"author_name":"Florian Maier","author_url":"https:\/\/www.orpheus-magazin.de\/de\/author\/redaktionorpheus-magazin-de\/","author_email":"redaktion@orpheus-magazin.de","author_website":"","author_description":"","author_facebook":"","author_twitter":"","author_instagram":"","author_role":["administrator"],"author_firstname":"Florian","author_lastname":"Maier","user_login":"redaktion@orpheus-magazin.de","author_avatar":"<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/5ee5bbfa3e4d8e8fd4c1781cc619164177d374083eb6aa532bc9f2ba5f9c346a?s=200&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/5ee5bbfa3e4d8e8fd4c1781cc619164177d374083eb6aa532bc9f2ba5f9c346a?s=400&#038;d=mm&#038;r=g 2x' class='avatar avatar-200 photo' height='200' width='200' decoding='async'\/>","author_avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5ee5bbfa3e4d8e8fd4c1781cc619164177d374083eb6aa532bc9f2ba5f9c346a?s=96&d=mm&r=g","comment_count":0,"post_likes":0,"post_views":0},"tpgb_post_category":{"category":"<a href=\"https:\/\/www.orpheus-magazin.de\/de\/category\/rezensionen\/\" alt=\"Rezensionen\"  class=\"category-rezensionen\">Rezensionen<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/category\/rezensionen\/rezensionen-2025-03\/\" alt=\"Rezensionen 2025\/03\"  class=\"category-rezensionen-2025-03\">Rezensionen 2025\/03<\/a> "},"_links":{"self":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/posts\/10586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/comments?post=10586"}],"version-history":[{"count":0,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/posts\/10586\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/media\/10587"}],"wp:attachment":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/media?parent=10586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/categories?post=10586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/tags?post=10586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}