{"id":11537,"date":"2025-09-29T23:08:40","date_gmt":"2025-09-29T21:08:40","guid":{"rendered":"https:\/\/www.orpheus-magazin.de\/?p=11537"},"modified":"2025-09-30T14:03:50","modified_gmt":"2025-09-30T12:03:50","slug":"zuerich-der-rosenkavalier","status":"publish","type":"post","link":"https:\/\/www.orpheus-magazin.de\/de\/2025\/09\/29\/zuerich-der-rosenkavalier\/","title":{"rendered":"Vom Spiel mit der Verg\u00e4nglichkeit"},"content":{"rendered":"<p>Die Besetzung liest sich wie das \u201eBest-of\u201c der aktuell verf\u00fcgbaren Rollenprotagonisten, mit Joana Mallwitz steht eine der gefragtesten jungen Dirigentinnen am Pult des Orchesters der Oper Z\u00fcrich: Keine Frage, Matthias Schulz setzt mit Richard Strauss\u2019 \u201eRosenkavalier\u201c gleich zu Beginn seiner Intendanz ein schillerndes Glanzlicht.<\/p>\n\n\n\n<p>Und in diesem Fall ist die Spitzenbesetzung wahrlich kein Luxus: Mallwitz\u2019 temporeiche Interpretation verlangt vom routinierten Ensemble nicht selten halsbrecherische Wortakrobatik. Das bekommt vor allem Baron Ochs alias G\u00fcnther Groissb\u00f6ck im ersten Akt zu sp\u00fcren, dem f\u00fcr seine konversationsreiche Paraderolle buchst\u00e4blich wenig \u201eLuft zum Atmen\u201c bleibt. Dass er trotz zungenbrecherischem Einsatz pr\u00e4zise textverst\u00e4ndlich ist und bis hin zum T\u00eate-\u00e0-T\u00eate mit Mariandl im SM-Studio (dritter Aufzug) sogar noch mit kom\u00f6diantischem Talent darstellerische H\u00f6hepunkte setzen kann, beweist seine Klasse.<\/p>\n\n\n\n<p>Diana Damrau als Marschallin liefert eine Art Kontrapunkt dazu, sie versteht es meisterhaft, inmitten von optischer und musikalischer Hyper-Opulenz ihre lyrischen, tragischen und nachdenklichen Momente stimmlich voll auszukosten. Etwas, das Mallwitz\u2019 rasanter Lesart nach anf\u00e4nglicher H\u00f6r-Irritation einen spannenden, neuen Schwung verleiht. Die innerliche Wandlung der Marschallin bildet dann auch das psychologische Zentrum dieses allgegenw\u00e4rtig ver(sinn)bildlichten Vanitas-Effekts von Gottfried Helnwein. Sein opulentes Kost\u00fcm- und B\u00fchnenbild zeigt barockes Lebensgef\u00fchl zwischen \u00fcbertriebenem Glamour und l\u00e4cherlicher Farce.<\/p>\n\n\n\n<p>Musikalisch gipfelt die Strauss\u2019sche F\u00fclle vor allem im Liebesduett von Octavian und Sophie sowie im finalen Terzett \u2013 hier nimmt sich das optische Geschehen merklich zur\u00fcck, puristisches Hellblau oder eine abgedunkelte Sternenhimmel-Kulisse gen\u00fcgen. F\u00fcr Lydia Steier, die eine Produktion der Los Angeles Opera aus dem Jahr 2005 neu inszenierte, liegt der Fokus in erster Linie auf lebendigerer Personenregie \u2013 mit Erfolg. Sie trifft den richtigen Ton und jongliert die Protagonisten gekonnt inmitten dieser unkontrollierbaren Welt aus \u00fcberbordend-opulenter Musik, phantastischer Wollust und inhaltlichem Wahnsinn. Und sie setzt Akzente: W\u00e4hrend Angela Browers Octavian sich darstellerisch vom st\u00f6rrischen Rosen-\u00dcberbringer zum mitleidenden, jugendlichen Liebhaber entwickeln darf \u2013 ihre s\u00e4ngerischen Qualit\u00e4ten sind die \u00dcberraschung des Abends \u2013, ist die US-Amerikanerin Emily Pogorelc bei Steier eine freche, selbstbewusste und entgegen der \u00fcblichen Rollentradition sogar aufm\u00fcpfige Sophie. Dass sie das mit m\u00e4dchenhaftem, klarem Sopran tut, passt zu dieser vor Kontroversen strotzenden Produktion. Bo Skovhus als Faninal bleibt dagegen insgesamt etwas blass, was aber nicht weiter tragisch ist.<\/p>\n\n\n\n<p>Das Konzept geht auf, die Geschichte balanciert gekonnt \u00fcberspitzt bis an den Rand der Persiflage, ohne ins Oberfl\u00e4chliche abzudriften. Wer die US-Netflix-Serie \u201eBridgerton\u201c kennt, wird sich in dieser \u00c4sthetik \u00fcbrigens wie zu Hause f\u00fchlen.<\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>Iris Steiner<\/em><\/p>\n\n\n\n<p><strong>\u201eDer Rosenkavalier\u201c (1911) \/\/ Kom\u00f6die f\u00fcr Musik von Richard Strauss<\/strong><\/p>\n\n\n\n<p><a href=\"https:\/\/www.opernhaus.ch\/spielplan\/kalendarium\/der-rosenkavalier\/2025-2026\/\" target=\"_blank\" rel=\"noreferrer noopener\">Infos und Termine auf der Website des Opernhauses Z\u00fcrich<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/www.arte.tv\/de\/videos\/126459-000-A\/richard-strauss-der-rosenkavalier\/\" target=\"_blank\" rel=\"noreferrer noopener\">kostenfreier Stream bis 20. Januar 2026 auf arte.tv<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p><span class=\"location\"> Z\u00fcrich \/ Opernhaus Z\u00fcrich (September 2025)<\/span><\/br> Opulente \u201eBridgerton\u201c-\u00c4sthetik f\u00fcr den \u201eRosenkavalier\u201c<\/p>","protected":false},"author":12,"featured_media":11539,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"tpgb_global_settings":"","_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_eb_attr":"","footnotes":""},"categories":[34,1916],"tags":[],"class_list":["post-11537","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rezensionen","category-rezensionen-2025-06"],"tpgb_featured_images":{"full":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2025\/09\/Opernhaus-Zuerich_Der-Rosenkavalier-c-Matthias-Baus.jpg",1500,844,false],"tp-image-grid":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2025\/09\/Opernhaus-Zuerich_Der-Rosenkavalier-c-Matthias-Baus-700x700.jpg",700,700,true],"thumbnail":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2025\/09\/Opernhaus-Zuerich_Der-Rosenkavalier-c-Matthias-Baus-150x150.jpg",150,150,true],"medium":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2025\/09\/Opernhaus-Zuerich_Der-Rosenkavalier-c-Matthias-Baus-300x169.jpg",300,169,true],"medium_large":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2025\/09\/Opernhaus-Zuerich_Der-Rosenkavalier-c-Matthias-Baus-768x432.jpg",600,338,true],"large":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2025\/09\/Opernhaus-Zuerich_Der-Rosenkavalier-c-Matthias-Baus-1024x576.jpg",600,338,true],"default":"https:\/\/www.orpheus-magazin.de\/wp-content\/plugins\/the-plus-addons-for-block-editor\/assets\/images\/tpgb-placeholder.jpg"},"tpgb_post_meta_info":{"get_date":"29. September 2025","get_modified_date":"30. September 2025","category_list":{"category":[{"term_id":34,"name":"Rezensionen","slug":"rezensionen","term_group":0,"term_taxonomy_id":34,"taxonomy":"category","description":"","parent":0,"count":507,"filter":"raw","order":"0"},{"term_id":1916,"name":"Rezensionen 2025\/06","slug":"rezensionen-2025-06","term_group":0,"term_taxonomy_id":1916,"taxonomy":"category","description":"","parent":34,"count":13,"filter":"raw","order":"0"}],"post_tag":false},"author_name":"Florian Maier","author_url":"https:\/\/www.orpheus-magazin.de\/de\/author\/redaktionorpheus-magazin-de\/","author_email":"redaktion@orpheus-magazin.de","author_website":"","author_description":"","author_facebook":"","author_twitter":"","author_instagram":"","author_role":["administrator"],"author_firstname":"Florian","author_lastname":"Maier","user_login":"redaktion@orpheus-magazin.de","author_avatar":"<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/5ee5bbfa3e4d8e8fd4c1781cc619164177d374083eb6aa532bc9f2ba5f9c346a?s=200&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/5ee5bbfa3e4d8e8fd4c1781cc619164177d374083eb6aa532bc9f2ba5f9c346a?s=400&#038;d=mm&#038;r=g 2x' class='avatar avatar-200 photo' height='200' width='200' decoding='async'\/>","author_avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5ee5bbfa3e4d8e8fd4c1781cc619164177d374083eb6aa532bc9f2ba5f9c346a?s=96&d=mm&r=g","comment_count":0,"post_likes":0,"post_views":0},"tpgb_post_category":{"category":"<a href=\"https:\/\/www.orpheus-magazin.de\/de\/category\/rezensionen\/\" alt=\"Rezensionen\"  class=\"category-rezensionen\">Rezensionen<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/category\/rezensionen\/rezensionen-2025-06\/\" alt=\"Rezensionen 2025\/06\"  class=\"category-rezensionen-2025-06\">Rezensionen 2025\/06<\/a> "},"_links":{"self":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/posts\/11537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/comments?post=11537"}],"version-history":[{"count":0,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/posts\/11537\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/media\/11539"}],"wp:attachment":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/media?parent=11537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/categories?post=11537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/tags?post=11537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}