{"id":11671,"date":"2025-11-04T15:35:19","date_gmt":"2025-11-04T14:35:19","guid":{"rendered":"https:\/\/www.orpheus-magazin.de\/?p=11671"},"modified":"2025-12-21T20:40:29","modified_gmt":"2025-12-21T19:40:29","slug":"kassel-aida","status":"publish","type":"post","link":"https:\/\/www.orpheus-magazin.de\/de\/2025\/11\/04\/kassel-aida\/","title":{"rendered":"\u201eAida\u201c auf der AIDA"},"content":{"rendered":"<p>Es riecht noch nach frischer Farbe. Gerade einmal 18 Monate waren es von der ersten Idee bis zur Er\u00f6ffnung des \u201eInterim\u201c, der Ersatzspielst\u00e4tte des Kasseler Opernhauses w\u00e4hrend der technischen Sanierung. Intendant und Regisseur Florian Lutz zeigt zur Er\u00f6ffnung mit Giuseppe Verdis \u201eAida\u201c, was der Multifunktionsraum kann.<\/p>\n\n\n\n<p>Der modulare Theaterbau \u2013 komplett r\u00fcckbaubar zur Wiederverwendung an anderen Orten \u2013 bietet mit einem B\u00fchnenraum von 25 mal 50 Metern und einer H\u00f6he von 18 Metern Platz f\u00fcr bis zu 850 G\u00e4ste. Der Holzboden erstreckt sich \u00fcber die gesamte Fl\u00e4che, die Obermaschinerie mit 28 Z\u00fcgen \u00fcber die komplette Rauml\u00e4nge. Im Boden eingelassen sind ein variabler Orchestergraben und eine Schwerlast-Drehscheibe. Eine umlaufende Ger\u00fcstgalerie dient als Spielfl\u00e4che und Zuschauerraum. Die flexiblen Sitztrib\u00fcnen bieten unterschiedliche Varianten: Guckkasten, Raumb\u00fchne und immersive Arena. Bei \u201eAida\u201c steht die Trib\u00fcne auf der Drehscheibe, die die Zuschauer um 180 Grad zu einer Spielfl\u00e4che im Hintergrund bewegt.<\/p>\n\n\n\n<p>Verdis Oper spielt auf dem gleichnamigen Kreuzfahrtschiff. Chor und Statisten bev\u00f6lkern auf Liegest\u00fchlen das Sonnendeck im B\u00fchnenraum von Sebastian Hannak. Darunter sind auch einige Zuschauerinnen und Zuschauer \u2013 man kann \u201eAdventure-Sitze\u201c an der Bar und im Restaurant buchen, gef\u00fchrte Ortswechsel durch \u201eCrewmitglieder\u201c inbegriffen.<\/p>\n\n\n\n<p>Statt \u00e4gyptischen Pyramiden gibt es Politik an Bord (Kost\u00fcme: Mechthild Feuerstein). Heerf\u00fchrer Radam\u00e8s (Gabriele Mangione) wird zu Wolodymyr Selenskyj, Priester Ramfis (Sebastian Pilgrim) ist Donald Trump. Als Priesterin (Daniela Vega) erleben wir Ursula von der Leyen, der \u00e4gyptische K\u00f6nig (Ian Sidden) ist Frank-Walter Steinmeier. Aidas Vater Amonasro (Filippo Bettoschi) erinnert an Putin \u2013 inklusive filmischem Pferderitt. Aidas Rivalin Amneris, hinrei\u00dfend dargestellt von Emanuela Pascu, kommt mit einem Porsche auf die B\u00fchne gerollt. Aida arbeitet als Servicekraft auf dem Luxusschiff. Sie wird von Ilaria Alida Quilico grandios in ihrer Zerrissenheit zwischen Liebe und Loyalit\u00e4t dargestellt. Leinw\u00e4nde und Bildschirme (Videos: Konrad K\u00e4stner) untermalen jede Sekunde mit gro\u00dffl\u00e4chigen Projektionen: Nachrichtenschnipsel, Livebilder und KI-generierte Sequenzen.<\/p>\n\n\n\n<p>Das Staatsorchester Kassel unter Leitung von Ain\u0101rs Rubi\u0137is \u00fcberzeugt schon bei den ersten leisen T\u00f6nen und f\u00fcllt den Raum auch in den kraftvollen Momenten. Gerade die Abstimmung zwischen Orchester und den \u00fcberall im Raum befindlichen Solisten gelingt und schafft \u2013 je nach Sitzplatz \u2013 ungew\u00f6hnliche G\u00e4nsehautmomente. Es ist schon etwas Besonderes, wenn der sich gerade noch neben einem an der \u201eSchiffsbar\u201c befindliche Mensch nicht als Zuschauer, sondern als Chors\u00e4nger entpuppt (hervorragend einstudiert von Marco Zeiser Celesti und Anne-Louise Bourbion). Fast m\u00f6chte man mitsingen und mitspielen.<\/p>\n\n\n\n<p>Der Start ist gelungen \u2013 es gibt freundlichen Applaus, einige Buhs f\u00fcr die Inszenierung und Jubel f\u00fcr die musikalische Seite des Abends.<\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>Marcus Leitschuh<\/em><\/p>\n\n\n\n<p><strong>\u201eAida\u201c (1871) \/\/ Oper von Giuseppe Verdi<\/strong><\/p>\n\n\n\n<p><a href=\"https:\/\/www.staatstheater-kassel.de\/play\/aida-3257\" target=\"_blank\" rel=\"noreferrer noopener\">Infos und Termine auf der Website des Staatstheaters Kassel<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p><span class=\"location\"> Staatstheater Kassel \u2022 Aida<\/span><\/br> Das neue \u201eInterim\u201c bietet im Multifunktionsraum fast schon zu viel <\/p>","protected":false},"author":12,"featured_media":11674,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"tpgb_global_settings":"","_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_eb_attr":"","footnotes":""},"categories":[1922,34],"tags":[],"class_list":["post-11671","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rezensionen-2026-01","category-rezensionen"],"tpgb_featured_images":{"full":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2025\/11\/Staatstheater-Kassel_Aida-c-Sebastian-Hannak.jpg",1500,844,false],"tp-image-grid":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2025\/11\/Staatstheater-Kassel_Aida-c-Sebastian-Hannak-700x700.jpg",700,700,true],"thumbnail":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2025\/11\/Staatstheater-Kassel_Aida-c-Sebastian-Hannak-150x150.jpg",150,150,true],"medium":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2025\/11\/Staatstheater-Kassel_Aida-c-Sebastian-Hannak-300x169.jpg",300,169,true],"medium_large":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2025\/11\/Staatstheater-Kassel_Aida-c-Sebastian-Hannak-768x432.jpg",600,338,true],"large":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2025\/11\/Staatstheater-Kassel_Aida-c-Sebastian-Hannak-1024x576.jpg",600,338,true],"default":"https:\/\/www.orpheus-magazin.de\/wp-content\/plugins\/the-plus-addons-for-block-editor\/assets\/images\/tpgb-placeholder.jpg"},"tpgb_post_meta_info":{"get_date":"4. November 2025","get_modified_date":"21. Dezember 2025","category_list":{"category":[{"term_id":1922,"name":"Rezensionen 2026\/01","slug":"rezensionen-2026-01","term_group":0,"term_taxonomy_id":1922,"taxonomy":"category","description":"","parent":34,"count":8,"filter":"raw","order":"0"},{"term_id":34,"name":"Rezensionen","slug":"rezensionen","term_group":0,"term_taxonomy_id":34,"taxonomy":"category","description":"","parent":0,"count":507,"filter":"raw","order":"0"}],"post_tag":false},"author_name":"Florian Maier","author_url":"https:\/\/www.orpheus-magazin.de\/de\/author\/redaktionorpheus-magazin-de\/","author_email":"redaktion@orpheus-magazin.de","author_website":"","author_description":"","author_facebook":"","author_twitter":"","author_instagram":"","author_role":["administrator"],"author_firstname":"Florian","author_lastname":"Maier","user_login":"redaktion@orpheus-magazin.de","author_avatar":"<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/5ee5bbfa3e4d8e8fd4c1781cc619164177d374083eb6aa532bc9f2ba5f9c346a?s=200&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/5ee5bbfa3e4d8e8fd4c1781cc619164177d374083eb6aa532bc9f2ba5f9c346a?s=400&#038;d=mm&#038;r=g 2x' class='avatar avatar-200 photo' height='200' width='200' decoding='async'\/>","author_avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5ee5bbfa3e4d8e8fd4c1781cc619164177d374083eb6aa532bc9f2ba5f9c346a?s=96&d=mm&r=g","comment_count":0,"post_likes":0,"post_views":0},"tpgb_post_category":{"category":"<a href=\"https:\/\/www.orpheus-magazin.de\/de\/category\/rezensionen\/rezensionen-2026-01\/\" alt=\"Rezensionen 2026\/01\"  class=\"category-rezensionen-2026-01\">Rezensionen 2026\/01<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/category\/rezensionen\/\" alt=\"Rezensionen\"  class=\"category-rezensionen\">Rezensionen<\/a> "},"_links":{"self":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/posts\/11671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/comments?post=11671"}],"version-history":[{"count":1,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/posts\/11671\/revisions"}],"predecessor-version":[{"id":12567,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/posts\/11671\/revisions\/12567"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/media\/11674"}],"wp:attachment":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/media?parent=11671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/categories?post=11671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/tags?post=11671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}