{"id":3300,"date":"2020-12-23T19:14:00","date_gmt":"2020-12-23T18:14:00","guid":{"rendered":"https:\/\/www.orpheus-magazin.de\/?p=3300"},"modified":"2021-01-03T11:03:52","modified_gmt":"2021-01-03T10:03:52","slug":"russisches-seelendrama","status":"publish","type":"post","link":"https:\/\/www.orpheus-magazin.de\/de\/2020\/12\/23\/russisches-seelendrama\/","title":{"rendered":"Russisches Seelendrama"},"content":{"rendered":"<p>Die dritte Saison-Premiere an der Wiener Staatsoper beginnt zwei Tage zuvor mit einem unfreiwilligen Paukenschlag: F\u00fcr Tamuna Gochashvili muss rasch eine neue Tatjana gefunden werden \u2013 Nicole Car springt ein und gibt ihr Hausdeb\u00fct vor ihrer geplanten \u201eFaust\u201c-Auff\u00fchrung im n\u00e4chsten April. Die Australierin schafft bei ihrem Sprung ins kalte Wasser eine einf\u00fchlsame Darstellung als \u201eblasse Traurige und Schweigsame\u201c. Die Briefszene gelingt dem sch\u00f6nklingenden Sopran vorz\u00fcglich mit ihrer dunklen Mittellage, aus der hohe T\u00f6ne kraftvoll zu leuchten beginnen. Auch wenn es absolut unm\u00f6glich gewesen w\u00e4re, dass eine Frau im Russland des 18. Jahrhunderts den Dialog beginnt und einen hei\u00dfbl\u00fctigen Liebesbrief \u201ean den Schutzengel oder heimt\u00fcckischen Verehrer\u201c schreibt, kann der intensive Vortrag voller Zweifel und mit umfassender Zartheit ber\u00fchren. Unverst\u00e4ndlich ist nur, warum bei einem der H\u00f6hepunkte dieses Abends die Sessel an dem Tisch lautstark umfallen m\u00fcssen \u2013 Tatjanas Gef\u00fchlsausbruch w\u00e4re auch ohne diesen L\u00e4rm glaubw\u00fcrdig genug gewesen. Hausdeb\u00fctant Andr\u00e8 Schuen bietet vokal und darstellerisch eine solide Leistung, mitrei\u00dfen kann sein Onegin aber mit wenig Leidenschaft (auch im letzten Akt) und seinem unauff\u00e4lligen Bariton nicht; gut gefallen seine zur Schau gestellte Eitelkeit und K\u00fchle. Brillant erlebt man hingegen Bogdan Volkov, der f\u00fcr die Rezensentin vom jugendlichen, feingliedrigen Aussehen und mit seiner eindringlichen Interpretation der ideale tr\u00e4umerische, sensible und tragische Lenski ist. Nach Olgas Koketterie ist der Dichter zutiefst verletzt und singt \u2013 in dieser Produktion \u2013 das Couplet von Triquet. Dies gelingt stimmlich famos und passt auch inhaltlich treffend, um einen Lenski zu zeigen, der \u2013 nach seinem empfunden gro\u00dfen Drama \u2013 Aufmerksamkeit sucht und geliebt werden will (auch wenn er sich dabei l\u00e4cherlich macht). Schwerm\u00fctig nimmt der russische Tenor bei \u201eKuda, Kuda\u201c mit zarten pianissimi und sentimentaler H\u00f6he Abschied vom Leben und den entschwundenen Tagen seiner goldenen Jugend \u2013 ein fantastischer Glanzpunkt des Abends, bevor sich nach einem Gerangel mit Onegin an dem langen Tisch des Einheitsb\u00fchnenbildes ein t\u00f6dlicher Schuss l\u00f6st. Als sein \u201eausgelassenes V\u00f6gelchen\u201c Olga spielt die kokette Anna Goryachova mit frischem, dunklen Mezzo keineswegs das unschuldige M\u00e4dchen, sondern wirkt mit Kaltschn\u00e4uzigkeit sehr herablassend gegen\u00fcber ihrem Verlobten. Die Rolle des F\u00fcrsten Gremin ist dankbar: Der noble Russe Dimitry Ivashchenko kann sich zwei Akte vorbereiten, singt seine Arie mit sonorer Tiefe und Ausdrucksst\u00e4rke, r\u00e4umt ab und bekommt f\u00fcr sein sch\u00f6nes Liebesgest\u00e4ndnis auch noch den Sopran. Eine starke Leistung bietet Larissa Diadkova als Amme Filipjewna, die ungl\u00fccklich von ihrer erzwungenen Eheschlie\u00dfung im 13. Lebensjahr erz\u00e4hlt.<\/p>\n\n\n\n<p>Das Dirigat unter Tom\u00e1\u0161 Hanus bringt den lyrischen Charakter gut heraus, die intensiven Streicher neigen zur Melancholie und die dramatischen Steigerungen brechen lautstark aus. Regie und B\u00fchnenbild von Dmitri Tcherniakov wurden 2006 f\u00fcr das Bolshoi-Theater Moskau kreiert und waren bereits in Paris, London, New York und Tokio zu sehen. An einem riesigen Tisch wird gegessen, getr\u00e4umt, getrunken oder man duelliert sich. Die Personenf\u00fchrung wird bis ins kleinste Detail gezeichnet und zeigt spannende Charakterstudien \u00fcber die Trag\u00f6dien von Tatjana, Onegin und Lenski. Das Publikum ist vor allem erfreut, die ungeliebte Inszenierung von Falk Richter losgeworden zu sein, und das ausverkaufte Haus inklusive Pl\u00e1cido Domingo jubelt.<\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>Susanne Lukas<\/em><\/p>\n\n\n\n<p><strong>\u201eEugen Onegin\u201c (1879) \/\/ Pjotr I. Tschaikowski<\/strong><br><\/p>","protected":false},"excerpt":{"rendered":"<p><span class=\"location\">Wien \/ Wiener Staatsoper (Oktober 2020)<\/span><\/br><br \/>\n\u201eEugen Onegin\u201c in unspektakul\u00e4rem Einheitsb\u00fchnenbild<\/p>","protected":false},"author":0,"featured_media":3582,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"tpgb_global_settings":"","_editorskit_title_hidden":false,"_editorskit_reading_time":2,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_eb_attr":"","footnotes":""},"categories":[34,235],"tags":[285,286,159,140],"class_list":["post-3300","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rezensionen","category-rezensionen_2021_01","tag-eugen-onegin-1879","tag-pjotr-i-tschaikowski","tag-wien","tag-wiener-staatsoper"],"tpgb_featured_images":{"full":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2020\/12\/fsg_wien_eugen-onegin-eugenonegin_d5B1947_CAR_IVASHCHENKO_SCHUEN_c_wiener-staatsoper_michael-Poehn_16_9.jpg",1024,578,false],"tp-image-grid":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2020\/12\/fsg_wien_eugen-onegin-eugenonegin_d5B1947_CAR_IVASHCHENKO_SCHUEN_c_wiener-staatsoper_michael-Poehn_16_9-700x700.jpg",700,700,true],"thumbnail":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2020\/12\/fsg_wien_eugen-onegin-eugenonegin_d5B1947_CAR_IVASHCHENKO_SCHUEN_c_wiener-staatsoper_michael-Poehn_16_9-600x169.jpg",600,169,true],"medium":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2020\/12\/fsg_wien_eugen-onegin-eugenonegin_d5B1947_CAR_IVASHCHENKO_SCHUEN_c_wiener-staatsoper_michael-Poehn_16_9-300x169.jpg",300,169,true],"medium_large":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2020\/12\/fsg_wien_eugen-onegin-eugenonegin_d5B1947_CAR_IVASHCHENKO_SCHUEN_c_wiener-staatsoper_michael-Poehn_16_9-768x434.jpg",600,339,true],"large":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2020\/12\/fsg_wien_eugen-onegin-eugenonegin_d5B1947_CAR_IVASHCHENKO_SCHUEN_c_wiener-staatsoper_michael-Poehn_16_9.jpg",600,339,false],"default":"https:\/\/www.orpheus-magazin.de\/wp-content\/plugins\/the-plus-addons-for-block-editor\/assets\/images\/tpgb-placeholder.jpg"},"tpgb_post_meta_info":{"get_date":"23. Dezember 2020","get_modified_date":"3. Januar 2021","category_list":{"category":[{"term_id":34,"name":"Rezensionen","slug":"rezensionen","term_group":0,"term_taxonomy_id":34,"taxonomy":"category","description":"","parent":0,"count":507,"filter":"raw","order":"0"},{"term_id":235,"name":"Rezensionen 2021\/01","slug":"rezensionen_2021_01","term_group":0,"term_taxonomy_id":235,"taxonomy":"category","description":"","parent":34,"count":12,"filter":"raw","order":"0"}],"post_tag":[{"term_id":285,"name":"\u201eEugen Onegin\u201c (1879)","slug":"eugen-onegin-1879","term_group":0,"term_taxonomy_id":285,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","order":"0"},{"term_id":286,"name":"Pjotr I. Tschaikowski","slug":"pjotr-i-tschaikowski","term_group":0,"term_taxonomy_id":286,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","order":"0"},{"term_id":159,"name":"Wien","slug":"wien","term_group":0,"term_taxonomy_id":159,"taxonomy":"post_tag","description":"","parent":0,"count":8,"filter":"raw","order":"0"},{"term_id":140,"name":"Wiener Staatsoper","slug":"wiener-staatsoper","term_group":0,"term_taxonomy_id":140,"taxonomy":"post_tag","description":"","parent":0,"count":9,"filter":"raw","order":"0"}]},"comment_count":0,"post_likes":0,"post_views":0},"tpgb_post_category":{"category":"<a href=\"https:\/\/www.orpheus-magazin.de\/de\/category\/rezensionen\/\" alt=\"Rezensionen\"  class=\"category-rezensionen\">Rezensionen<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/category\/rezensionen\/rezensionen_2021_01\/\" alt=\"Rezensionen 2021\/01\"  class=\"category-rezensionen_2021_01\">Rezensionen 2021\/01<\/a> ","post_tag":"<a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/eugen-onegin-1879\/\" alt=\"\u201eEugen Onegin\u201c (1879)\"  class=\"post_tag-eugen-onegin-1879\">\u201eEugen Onegin\u201c (1879)<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/pjotr-i-tschaikowski\/\" alt=\"Pjotr I. Tschaikowski\"  class=\"post_tag-pjotr-i-tschaikowski\">Pjotr I. Tschaikowski<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/wien\/\" alt=\"Wien\"  class=\"post_tag-wien\">Wien<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/wiener-staatsoper\/\" alt=\"Wiener Staatsoper\"  class=\"post_tag-wiener-staatsoper\">Wiener Staatsoper<\/a> "},"_links":{"self":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/posts\/3300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/comments?post=3300"}],"version-history":[{"count":0,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/posts\/3300\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/media\/3582"}],"wp:attachment":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/media?parent=3300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/categories?post=3300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/tags?post=3300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}