{"id":4930,"date":"2021-02-16T12:26:06","date_gmt":"2021-02-16T11:26:06","guid":{"rendered":"https:\/\/www.orpheus-magazin.de\/?p=4930"},"modified":"2021-02-16T14:46:46","modified_gmt":"2021-02-16T13:46:46","slug":"nuancenreiches-welttheater","status":"publish","type":"post","link":"https:\/\/www.orpheus-magazin.de\/de\/2021\/02\/16\/nuancenreiches-welttheater\/","title":{"rendered":"Nuancenreiches Welttheater"},"content":{"rendered":"<p>Ja, es ist schon toll, wenn \u00fcber einhundert Mann Wagners \u201eWalk\u00fcrenritt\u201c oder den \u201eTrauermarsch\u201c hinfetzen. Doch dann gibt es die eine K\u00fcnstlerin auf der weiten, leeren B\u00fchne des M\u00fcnchner Nationaltheaters, die die ganze Welt erstehen l\u00e4sst. Der Rezensent hob am Ende sein Glas und verneigte sich vor dem Bildschirm \u2026<\/p>\n\n\n\n<p>Igor Strawinskys genre\u00fcbergreifendes Mini-Opus f\u00fcr sieben Instrumentalisten, einen Dirigenten, drei Darsteller und einen Vorleser sollte im Herbst 1918 die Theatern\u00f6te irgendwie \u00fcberbr\u00fccken. Denn auch in der neutralen Schweiz herrschte Mangel allenthalben. In Anlehnung an ein russisches M\u00e4rchen schuf Librettist Charles Ramuz ein Gleichnis: Ein armer Soldat hat Urlaub; der Teufel bittet um drei Tage Geigenunterricht im Tausch f\u00fcr ein Reichtum bringendes Buch; durch teuflische T\u00e4uschung werden daraus drei Jahre; niemand im Dorf erkennt den Soldaten und seine Liebste ist l\u00e4ngst verheiratete Mutter; entt\u00e4uscht nutzt der Soldat den Buchzauber und wird ein reicher Mann \u2013 nur ohne Liebe; doch als er dem betrunken gemachten Teufel die Geige abgewinnt und mit deren Kl\u00e4ngen die kranke Prinzessin heilt, scheint sein Gl\u00fcck vollkommen; nur will die Prinzessin seine Heimat kennenlernen, in die er nicht zur\u00fcckkehren darf; als er es ihr zuliebe doch tut, holt ihn der Teufel. \u201eMan soll zu dem, was man besitzt, begehren nicht, was fr\u00fcher war. Man kann zugleich nicht der sein, der man ist und der man war. Man kann nicht alles haben. Was war, kehrt nicht zur\u00fcck.\u201c<\/p>\n\n\n\n<p>Was moralinsauer daherkommen k\u00f6nnte, wurde zum stupenden kleinen Welttheater von heute. Zwar blieb die Schwarz-Wei\u00df-Filmfahrt durch die Leopold-Ludwigstra\u00dfe des ungenannt bleibenden Szenikers im Theaterrund v\u00f6llig verzichtbar. Zwar blieben Norbert Grafs kleine Tanzeinlagen ebenfalls belangloses Beiwerk. Doch da stand der kommende Generalmusikdirektor Vladimir Jurowski in lockerem Abstand zu seinen sieben Instrumentalsolisten. In klarer Zeichengebung, die Akzente setzte oder mit erhobenem Arm eine hohe Klarinettenlinie beschwor, erklangen Strawinskys kleine Genieblitze lange vor aller Moderne der 1920er Jahre: geradezu melodi\u00f6se Marschrhythmen, kontrastreiche Streitmusik, ein kleines Jubelkonzert beim Wiedergewinn der Geige \u2013 stellvertretend f\u00fcr seine exzellenten Kollegen muss Violinist Davis Schulthei\u00df genannt werden, der mal h\u00f6lzern kratzig, mal dramatisch zupackend, mal s\u00fc\u00df schwelgerisch die handlungstragend wechselnde Macht der Musik erklingen lie\u00df. Da stellte sich lange vor Brechts bem\u00fchtem Theoriebau so etwas wie \u201eepische Musik, die Distanz und Nachdenken beschw\u00f6rt\u201c als Assoziation ein. Zurecht signalisierte Jurowski schon am Ende des ersten Teils mit gezieltem Augenschlie\u00dfen seine Zustimmung \u2013 ansonsten gen\u00fcgte durchweg ein kurzer Blick hin\u00fcber an das einzelne Mikrofon.<\/p>\n\n\n\n<p>Da stand auch nur eine Person: Multitalent Dagmar Manzel lie\u00df sich aus Berlin an die Isar locken \u2013 und beschwor: ausmalenden Erz\u00e4hler, naiv-schlichten Soldaten, lockenden Teufel, br\u00fcllenden Marktschreier, alten K\u00f6nig, trunken lallenden Teufel, liebevolle Prinzessin und vermeintlich souver\u00e4nen reichen Mann, final tobenden Teufel \u2026 und zahllose weitere Nuancen als fesselnde Klangdramatik \u2013 ohne jegliches Getue, nur mit der Wandelbarkeit ihrer Stimme. Binnen Momenten entspann sich f\u00fcr fast eine Stunde eine ganze Lebenswelt, ohne Szene oder Kost\u00fcm, nur aus dem t\u00f6nend geformten und gef\u00e4rbten Wort. So muss das bei den gro\u00dfen Mimen und den lange Zeit dominierenden Erz\u00e4hlern von Epen bis hin zur Jahrmarkt-Moritat gewesen sein: Beschw\u00f6rung durch situativen Klang und aufgeladene Betonung \u2013 und Welt und Mensch sind imaginativ sichtbar. Strawinskys kleines Opus weitete sich zur Parabel, die auch auf uns zeigt. Das lie\u00df die Zweidimensionalit\u00e4t des Bildschirms vergessen. Hatten sich schon in der Minipause zwischen den zwei Werkteilen Manzel und Jurowski mit einem Glas zugeprostet, blieb am Ende nur das eigene Aufstehen, das Glas heben und tief beeindruckt danken: f\u00fcr ein singul\u00e4res Kabinettst\u00fcck, einen \u201eKunst-Brillanten\u201c, der lange weiterstrahlt \u2026 und dann zur\u00fcck in unsere Welt: eine Aufzeichnung auf DVD verdient!<\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>Wolf-Dieter Peter<\/em><\/p>\n\n\n\n<p><strong>\u201eL\u2019histoire du soldat\u201c (\u201eDie Geschichte vom Soldaten\u201c) (1918) \/\/ Igor Strawinsky<\/strong><\/p>\n\n\n\n<p><a href=\"https:\/\/www.staatsoper.de\/staatsopertv.html\" target=\"_blank\" aria-label=\"Die Inszenierung ist als Video-on-Demand ab 17. Februar 2021 f\u00fcr 30 Tage auf Staatsoper.TV abrufbar, ein 24-Stunden-Ticket kostet 4,90 Euro. (opens in a new tab)\" rel=\"noreferrer noopener\" class=\"ek-link\">Die Inszenierung ist als Video-on-Demand ab 17. Februar 2021 f\u00fcr 30 Tage auf Staatsoper.TV abrufbar, ein 24-Stunden-Ticket kostet 4,90 Euro.<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p><span class=\"location\">M\u00fcnchen \/ Bayerische Staatsoper (Februar 2021)<\/span><\/br><br \/>\nStrawinskys \u201eGeschichte vom Soldaten\u201c mit faszinierender Sprechk\u00fcnstlerin<\/p>","protected":false},"author":12,"featured_media":4931,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"tpgb_global_settings":"","_editorskit_title_hidden":false,"_editorskit_reading_time":2,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_eb_attr":"","footnotes":""},"categories":[34,444],"tags":[273,475,479,478,473,472,474,272,480,476,423,425,426,424,451,481,477],"class_list":["post-4930","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rezensionen","category-rezensionen-2021-02","tag-bayerische-staatsoper","tag-charles-ramuz","tag-dagmar-manzel","tag-david-schultheiss","tag-die-geschichte-vom-soldaten","tag-igor-strawinsky","tag-lhistoire-du-soldat","tag-muenchen","tag-musiktheater","tag-norbert-graf","tag-opernkritik","tag-orpheus","tag-orpheus-magazin","tag-premierenkritik","tag-streaming","tag-streamingkritik","tag-vladimir-jurowsi"],"tpgb_featured_images":{"full":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2021\/02\/FSG_Muenchen_Die-Geschichte-vom-Soldaten-Montagsstueck_XIV_A._Merkuri__C._Bastos_c__Hoesl__2_-c-Wilfried-Hoesl-scaled.jpg",2560,1706,false],"tp-image-grid":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2021\/02\/FSG_Muenchen_Die-Geschichte-vom-Soldaten-Montagsstueck_XIV_A._Merkuri__C._Bastos_c__Hoesl__2_-c-Wilfried-Hoesl-700x700.jpg",700,700,true],"thumbnail":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2021\/02\/FSG_Muenchen_Die-Geschichte-vom-Soldaten-Montagsstueck_XIV_A._Merkuri__C._Bastos_c__Hoesl__2_-c-Wilfried-Hoesl-600x200.jpg",600,200,true],"medium":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2021\/02\/FSG_Muenchen_Die-Geschichte-vom-Soldaten-Montagsstueck_XIV_A._Merkuri__C._Bastos_c__Hoesl__2_-c-Wilfried-Hoesl-1200x800.jpg",1200,800,true],"medium_large":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2021\/02\/FSG_Muenchen_Die-Geschichte-vom-Soldaten-Montagsstueck_XIV_A._Merkuri__C._Bastos_c__Hoesl__2_-c-Wilfried-Hoesl-768x512.jpg",600,400,true],"large":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2021\/02\/FSG_Muenchen_Die-Geschichte-vom-Soldaten-Montagsstueck_XIV_A._Merkuri__C._Bastos_c__Hoesl__2_-c-Wilfried-Hoesl-1920x1280.jpg",600,400,true],"default":"https:\/\/www.orpheus-magazin.de\/wp-content\/plugins\/the-plus-addons-for-block-editor\/assets\/images\/tpgb-placeholder.jpg"},"tpgb_post_meta_info":{"get_date":"16. Februar 2021","get_modified_date":"16. Februar 2021","category_list":{"category":[{"term_id":34,"name":"Rezensionen","slug":"rezensionen","term_group":0,"term_taxonomy_id":34,"taxonomy":"category","description":"","parent":0,"count":507,"filter":"raw","order":"0"},{"term_id":444,"name":"Rezensionen 2021\/02","slug":"rezensionen-2021-02","term_group":0,"term_taxonomy_id":444,"taxonomy":"category","description":"","parent":34,"count":11,"filter":"raw","order":"0"}],"post_tag":[{"term_id":273,"name":"Bayerische Staatsoper","slug":"bayerische-staatsoper","term_group":0,"term_taxonomy_id":273,"taxonomy":"post_tag","description":"","parent":0,"count":10,"filter":"raw","order":"0"},{"term_id":475,"name":"Charles Ramuz","slug":"charles-ramuz","term_group":0,"term_taxonomy_id":475,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","order":"0"},{"term_id":479,"name":"Dagmar Manzel","slug":"dagmar-manzel","term_group":0,"term_taxonomy_id":479,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","order":"0"},{"term_id":478,"name":"David Schulthei\u00df","slug":"david-schultheiss","term_group":0,"term_taxonomy_id":478,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","order":"0"},{"term_id":473,"name":"Die Geschichte vom Soldaten","slug":"die-geschichte-vom-soldaten","term_group":0,"term_taxonomy_id":473,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","order":"0"},{"term_id":472,"name":"Igor Strawinsky","slug":"igor-strawinsky","term_group":0,"term_taxonomy_id":472,"taxonomy":"post_tag","description":"","parent":0,"count":2,"filter":"raw","order":"0"},{"term_id":474,"name":"L\u2019histoire du soldat","slug":"lhistoire-du-soldat","term_group":0,"term_taxonomy_id":474,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","order":"0"},{"term_id":272,"name":"M\u00fcnchen","slug":"muenchen","term_group":0,"term_taxonomy_id":272,"taxonomy":"post_tag","description":"","parent":0,"count":9,"filter":"raw","order":"0"},{"term_id":480,"name":"Musiktheater","slug":"musiktheater","term_group":0,"term_taxonomy_id":480,"taxonomy":"post_tag","description":"","parent":0,"count":45,"filter":"raw","order":"0"},{"term_id":476,"name":"Norbert Graf","slug":"norbert-graf","term_group":0,"term_taxonomy_id":476,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","order":"0"},{"term_id":423,"name":"Opernkritik","slug":"opernkritik","term_group":0,"term_taxonomy_id":423,"taxonomy":"post_tag","description":"","parent":0,"count":42,"filter":"raw","order":"0"},{"term_id":425,"name":"orpheus","slug":"orpheus","term_group":0,"term_taxonomy_id":425,"taxonomy":"post_tag","description":"","parent":0,"count":83,"filter":"raw","order":"0"},{"term_id":426,"name":"Orpheus Magazin","slug":"orpheus-magazin","term_group":0,"term_taxonomy_id":426,"taxonomy":"post_tag","description":"","parent":0,"count":83,"filter":"raw","order":"0"},{"term_id":424,"name":"Premierenkritik","slug":"premierenkritik","term_group":0,"term_taxonomy_id":424,"taxonomy":"post_tag","description":"","parent":0,"count":56,"filter":"raw","order":"0"},{"term_id":451,"name":"Streaming","slug":"streaming","term_group":0,"term_taxonomy_id":451,"taxonomy":"post_tag","description":"","parent":0,"count":27,"filter":"raw","order":"0"},{"term_id":481,"name":"Streamingkritik","slug":"streamingkritik","term_group":0,"term_taxonomy_id":481,"taxonomy":"post_tag","description":"","parent":0,"count":33,"filter":"raw","order":"0"},{"term_id":477,"name":"Vladimir Jurowsi","slug":"vladimir-jurowsi","term_group":0,"term_taxonomy_id":477,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","order":"0"}]},"author_name":"Florian Maier","author_url":"https:\/\/www.orpheus-magazin.de\/de\/author\/redaktionorpheus-magazin-de\/","author_email":"redaktion@orpheus-magazin.de","author_website":"","author_description":"","author_facebook":"","author_twitter":"","author_instagram":"","author_role":["administrator"],"author_firstname":"Florian","author_lastname":"Maier","user_login":"redaktion@orpheus-magazin.de","author_avatar":"<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/5ee5bbfa3e4d8e8fd4c1781cc619164177d374083eb6aa532bc9f2ba5f9c346a?s=200&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/5ee5bbfa3e4d8e8fd4c1781cc619164177d374083eb6aa532bc9f2ba5f9c346a?s=400&#038;d=mm&#038;r=g 2x' class='avatar avatar-200 photo' height='200' width='200' decoding='async'\/>","author_avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5ee5bbfa3e4d8e8fd4c1781cc619164177d374083eb6aa532bc9f2ba5f9c346a?s=96&d=mm&r=g","comment_count":0,"post_likes":0,"post_views":0},"tpgb_post_category":{"category":"<a href=\"https:\/\/www.orpheus-magazin.de\/de\/category\/rezensionen\/\" alt=\"Rezensionen\"  class=\"category-rezensionen\">Rezensionen<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/category\/rezensionen\/rezensionen-2021-02\/\" alt=\"Rezensionen 2021\/02\"  class=\"category-rezensionen-2021-02\">Rezensionen 2021\/02<\/a> ","post_tag":"<a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/bayerische-staatsoper\/\" alt=\"Bayerische Staatsoper\"  class=\"post_tag-bayerische-staatsoper\">Bayerische Staatsoper<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/charles-ramuz\/\" alt=\"Charles Ramuz\"  class=\"post_tag-charles-ramuz\">Charles Ramuz<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/dagmar-manzel\/\" alt=\"Dagmar Manzel\"  class=\"post_tag-dagmar-manzel\">Dagmar Manzel<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/david-schultheiss\/\" alt=\"David Schulthei\u00df\"  class=\"post_tag-david-schultheiss\">David Schulthei\u00df<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/die-geschichte-vom-soldaten\/\" alt=\"Die Geschichte vom Soldaten\"  class=\"post_tag-die-geschichte-vom-soldaten\">Die Geschichte vom Soldaten<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/igor-strawinsky\/\" alt=\"Igor Strawinsky\"  class=\"post_tag-igor-strawinsky\">Igor Strawinsky<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/lhistoire-du-soldat\/\" alt=\"L\u2019histoire du soldat\"  class=\"post_tag-lhistoire-du-soldat\">L\u2019histoire du soldat<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/muenchen\/\" alt=\"M\u00fcnchen\"  class=\"post_tag-muenchen\">M\u00fcnchen<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/musiktheater\/\" alt=\"Musiktheater\"  class=\"post_tag-musiktheater\">Musiktheater<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/norbert-graf\/\" alt=\"Norbert Graf\"  class=\"post_tag-norbert-graf\">Norbert Graf<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/opernkritik\/\" alt=\"Opernkritik\"  class=\"post_tag-opernkritik\">Opernkritik<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/orpheus\/\" alt=\"orpheus\"  class=\"post_tag-orpheus\">orpheus<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/orpheus-magazin\/\" alt=\"Orpheus Magazin\"  class=\"post_tag-orpheus-magazin\">Orpheus Magazin<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/premierenkritik\/\" alt=\"Premierenkritik\"  class=\"post_tag-premierenkritik\">Premierenkritik<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/streaming\/\" alt=\"Streaming\"  class=\"post_tag-streaming\">Streaming<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/streamingkritik\/\" alt=\"Streamingkritik\"  class=\"post_tag-streamingkritik\">Streamingkritik<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/vladimir-jurowsi\/\" alt=\"Vladimir Jurowsi\"  class=\"post_tag-vladimir-jurowsi\">Vladimir Jurowsi<\/a> "},"_links":{"self":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/posts\/4930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/comments?post=4930"}],"version-history":[{"count":0,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/posts\/4930\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/media\/4931"}],"wp:attachment":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/media?parent=4930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/categories?post=4930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/tags?post=4930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}