{"id":5241,"date":"2021-02-28T18:50:00","date_gmt":"2021-02-28T17:50:00","guid":{"rendered":"https:\/\/www.orpheus-magazin.de\/?p=5241"},"modified":"2021-02-26T21:15:56","modified_gmt":"2021-02-26T20:15:56","slug":"kompendium-der-neueren-musik","status":"publish","type":"post","link":"https:\/\/www.orpheus-magazin.de\/de\/2021\/02\/28\/kompendium-der-neueren-musik\/","title":{"rendered":"Kompendium der neu(er)en Musik"},"content":{"rendered":"<p>Der \u00d6sterreicher Oswald Panagl, Jahrgang 1939, gro\u00dfer Opernfreund mit abgeschlossener Gesangsausbildung und Linguist, ist seit Jahrzehnten eine sichere Adresse f\u00fcr ultimative Kenntnis und profunde Einsichten zum Thema Musiktheater. Als emeritierter Professor f\u00fcr allgemeine und vergleichende Sprachwissenschaft an der Universit\u00e4t Salzburg ist er auch Essayist und Pr\u00e4sident der Internationalen Richard-Strauss-Gesellschaft. Er blickt auf einen umfangreichen Schatz von Monografien und Essays zur\u00fcck.<\/p>\n\n\n\n<p>Diejenigen, die sich mit der j\u00fcngeren Geschichte des Musiktheaters befassen, hat er zu einem hochinteressanten Kompendium zusammengestellt und in ebenso relevante wie aufhellende musikgeschichtliche Zusammenh\u00e4nge gebracht. Er wollte sich mit einer \u201eEpoche der neu(er)en Musik mit ihren Str\u00f6mungen, nationalen Variet\u00e4ten und wichtigen Repr\u00e4sentanten der einzelnen Sektoren und Stilrichtungen\u201c befassen und geht dabei von einer \u201elangen\u201c ersten H\u00e4lfte des 20. Jahrhunderts aus, die von einem gro\u00dfz\u00fcgig definierten Fin de Si\u00e8cle bis zur Avantgarde der fr\u00fchen 1950er Jahre reicht.<\/p>\n\n\n\n<p>Zun\u00e4chst geht Panagl auf die Definitionsproblematik dessen ein, was man unter \u201eModerne\u201c verstehen kann. Von einfachen Termini und Begriffen mit neuer Referenz und \u201emoderner\u201c Konnotation st\u00f6\u00dft er schlie\u00dflich auf die Erkenntnis, dass letzte Klarheit unm\u00f6glich ist. So m\u00f6ge man sich mit einem bekannten Spruch von J\u00fcrgen Habermas begn\u00fcgen: \u201eDie Moderne \u2013 ein unvollendetes Projekt.\u201c<\/p>\n\n\n\n<p>Zum Thema \u201eTraum in der Oper\u201c stellt er mit Werken von Debussy, Korngold und Martin\u016f ein kunstkritisches Szenario der Jahrhundertwende vor, das sich den Themen Symbolismus, Dekadenz, Nervenkunst, Traum und Wirklichkeit widmet \u2013 eine f\u00fcr jene Zeit bedeutsame Tendenz im \u201emodernen\u201c Musiktheater. Auf der Suche nach einer griffigen Formel f\u00fcr diese disparaten Momente kommt er auf einen Dramentitel aus dem 19. Jahrhundert: \u201eDer Traum ein Leben\u201c. Genau mit diesem Titel hat Walter Braunfels 1937 eine Oper komponiert.<\/p>\n\n\n\n<p>Vor dem zentralen Block mit Werken deutsch(sprachig)er Tondichter beginnt Panagl mit Giacomo Puccini wegen des innovativen Moments seiner Opern. \u201eLa boh\u00e8me\u201c ist mittlerweile vom \u201eLeitfossil des Nachmittagsabonnements\u201c zu einer Herausforderung f\u00fcr Regisseure geworden. \u201eTosca\u201c liegt im Spannungsfeld musikdramatischer Gattungen, und in \u201eTurandot\u201c sieht er ein neues Verh\u00e4ltnis der zwei S\u00e4ulen der \u201econditio humana\u201c: Der emotionale Weg von erlittenem Tod f\u00fchrt zu neu erwachter Liebe! F\u00fcr den ohnehin von Natur aus Getriebenen und Avantgardisten Ferruccio Busoni war das realistische Theater ein \u00e4sthetisches \u00c4rgernis. Er gab in seinem \u201eDoktor Faust\u201c entsprechende Antworten.<\/p>\n\n\n\n<p>Nat\u00fcrlich ist bei Oswald Panagl der Richard-Strauss-Teil der gr\u00f6\u00dfte. Das Geheimnis der Liebe und des Todes in \u201eSalome\u201c ist ein weiteres Beispiel der \u201eD\u00e9cadence\u201c um die Jahrhundertwende. Die \u201eModernit\u00e4t\u201c der Musiksprache der \u201eElektra\u201c zeichnet sich durch \u201epsychische Polyphonie\u201c aus. In \u201eAriadne auf Naxos\u201c erscheinen die so gegens\u00e4tzlichen Ariadne und Zerbinetta als in Wahrheit unterschiedliche Facetten des weiblichen Wesens (\u201eZerbiadne\u201c bzw. \u201eArietta\u201c), damit in eine neue Wahrnehmungsrichtung weisend. Diese ungew\u00f6hnliche Oper ergibt auch quasi ein neues Genre! Bei der \u201e\u00c4gyptischen Helena\u201c fragt er, ob es sich um ein untersch\u00e4tztes Meisterwerk oder ein missratenes Sorgenkind handelt. Im \u201eRosenkavalier\u201c stehen Beziehungsmuster und Sprachspiele im Gesamtkunstwerk im Vordergrund. Zu \u201eIntermezzo\u201c, bei dem die Liebe zur Autobiographie \u00fcberwiegt, stellt Panagl die Frage, ob das Werk ein Nachfahre b\u00fcrgerlicher Musikkultur oder Vorhut der Avantgarde sei. Bei \u201eArabella\u201c steht im Raum, ob es ein \u201eSklerosenkavalier\u201c oder szenische Realutopie ist \u2026<\/p>\n\n\n\n<p>In Hans Pfitzner sieht der Autor einen sp\u00e4tromantischen Gr\u00fcbler, einen Unzeitgem\u00e4\u00dfen an der Epochenschwelle, was auch in der Rolle des Palestrina zum Ausdruck kommt. Auch bei Pfitzner ist der Traum ein zentrales Element seines \u0152uvres. In einem gro\u00dfen \u201eerratischen Block\u201c aus M\u00e4hren zu Leo\u0161 Jan\u00e1\u010dek sieht der Autor besonders auf \u201eMenschliches, Allzumenschliches\u201c und die gro\u00dfen Frauenrollen, die das Schaffen dieses Komponisten kennzeichnen, sowie auf den f\u00fcr ihn so typischen Sprachmelos.<\/p>\n\n\n\n<p>Es folgt Interessantes zum modernen Musiktheater aus \u201eOst-Europa\u201c und zum literarischen Symbolismus sowie der impressionistischen Tonsprache von Claude Debussy. Kurt Weill und Benjamin Britten folgen mit einer Analyse zum \u201eLied der Stra\u00dfe und den Farben des Meeres\u201c als imagin\u00e4re Orte und zeitkritische Chiffre.<\/p>\n\n\n\n<p>Das Buch ist ein kaum enden wollender Fundus an oft unbekannten und interessanten Fakten und Einsichten. Gleichzeitig ist es ein umfassendes Nachschlagewerk zu einer bis in die Praxis des heutigen Musiktheaters wirkenden Epoche.<\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>Klaus Billand<\/em><\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile has-media-on-the-bottom has-background\" style=\"background-color:#b8881c\"><figure class=\"wp-block-media-text__media\"><\/figure><div class=\"wp-block-media-text__content\">\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-white-color has-text-color has-large-font-size\">INFOS ZUM BUCH<\/p>\n\n\n\n<p class=\"has-white-color has-text-color\">Oswald Panagl: \u201eIm Zeichen der Moderne. Musiktheater zwischen Fin de Si\u00e8cle und Avantgarde\u201c<br>422 Seiten, Hollitzer<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Oswald Panagl: \u201eIm Zeichen der Moderne. Musiktheater zwischen Fin de Si\u00e8cle und Avantgarde\u201c<\/p>","protected":false},"author":12,"featured_media":5216,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"tpgb_global_settings":"","_editorskit_title_hidden":false,"_editorskit_reading_time":2,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_eb_attr":"","footnotes":""},"categories":[223,579,580],"tags":[758,754,747,748,746,752,753,755,161,756,759,749,526,751,757,487,425,426,750,50,275],"class_list":["post-5241","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-medien","category-medien-2021-02","category-medien-2021-02-buch","tag-benjamin-britten","tag-bohuslav-martinu","tag-buchbesprechung","tag-buchkritik","tag-buchrezension","tag-claude-debussy","tag-erich-wolfgang-korngold","tag-ferruccio-busoni","tag-giacomo-puccini","tag-hans-pfitzner","tag-im-zeichen-der-moderne","tag-klassikbuch","tag-klaus-billand","tag-kompendium","tag-kurt-weill","tag-leos-janacek","tag-orpheus","tag-orpheus-magazin","tag-oswald-panagl","tag-richard-strauss","tag-walter-braunfels"],"tpgb_featured_images":{"full":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2021\/02\/Buch_Zeichen-der-Moderne.jpg",1440,887,false],"tp-image-grid":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2021\/02\/Buch_Zeichen-der-Moderne-700x700.jpg",700,700,true],"thumbnail":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2021\/02\/Buch_Zeichen-der-Moderne-600x185.jpg",600,185,true],"medium":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2021\/02\/Buch_Zeichen-der-Moderne-1200x739.jpg",1200,739,true],"medium_large":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2021\/02\/Buch_Zeichen-der-Moderne-768x473.jpg",600,370,true],"large":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2021\/02\/Buch_Zeichen-der-Moderne-1024x631.jpg",600,370,true],"default":"https:\/\/www.orpheus-magazin.de\/wp-content\/plugins\/the-plus-addons-for-block-editor\/assets\/images\/tpgb-placeholder.jpg"},"tpgb_post_meta_info":{"get_date":"28. Februar 2021","get_modified_date":"26. Februar 2021","category_list":{"category":[{"term_id":223,"name":"Medien","slug":"medien","term_group":0,"term_taxonomy_id":223,"taxonomy":"category","description":"","parent":0,"count":26,"filter":"raw","order":"0"},{"term_id":579,"name":"Medien 2021\/02","slug":"medien-2021-02","term_group":0,"term_taxonomy_id":579,"taxonomy":"category","description":"","parent":223,"count":9,"filter":"raw","order":"0"},{"term_id":580,"name":"Medien 2021\/02 Buch","slug":"medien-2021-02-buch","term_group":0,"term_taxonomy_id":580,"taxonomy":"category","description":"","parent":579,"count":2,"filter":"raw","order":"0"}],"post_tag":[{"term_id":758,"name":"Benjamin Britten","slug":"benjamin-britten","term_group":0,"term_taxonomy_id":758,"taxonomy":"post_tag","description":"","parent":0,"count":2,"filter":"raw","order":"0"},{"term_id":754,"name":"Bohuslav Martin\u016f","slug":"bohuslav-martinu","term_group":0,"term_taxonomy_id":754,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","order":"0"},{"term_id":747,"name":"Buchbesprechung","slug":"buchbesprechung","term_group":0,"term_taxonomy_id":747,"taxonomy":"post_tag","description":"","parent":0,"count":2,"filter":"raw","order":"0"},{"term_id":748,"name":"Buchkritik","slug":"buchkritik","term_group":0,"term_taxonomy_id":748,"taxonomy":"post_tag","description":"","parent":0,"count":2,"filter":"raw","order":"0"},{"term_id":746,"name":"Buchrezension","slug":"buchrezension","term_group":0,"term_taxonomy_id":746,"taxonomy":"post_tag","description":"","parent":0,"count":2,"filter":"raw","order":"0"},{"term_id":752,"name":"Claude Debussy","slug":"claude-debussy","term_group":0,"term_taxonomy_id":752,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","order":"0"},{"term_id":753,"name":"Erich Wolfgang Korngold","slug":"erich-wolfgang-korngold","term_group":0,"term_taxonomy_id":753,"taxonomy":"post_tag","description":"","parent":0,"count":2,"filter":"raw","order":"0"},{"term_id":755,"name":"Ferruccio Busoni","slug":"ferruccio-busoni","term_group":0,"term_taxonomy_id":755,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","order":"0"},{"term_id":161,"name":"Giacomo Puccini","slug":"giacomo-puccini","term_group":0,"term_taxonomy_id":161,"taxonomy":"post_tag","description":"","parent":0,"count":3,"filter":"raw","order":"0"},{"term_id":756,"name":"Hans Pfitzner","slug":"hans-pfitzner","term_group":0,"term_taxonomy_id":756,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","order":"0"},{"term_id":759,"name":"Im Zeichen der Moderne","slug":"im-zeichen-der-moderne","term_group":0,"term_taxonomy_id":759,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","order":"0"},{"term_id":749,"name":"Klassikbuch","slug":"klassikbuch","term_group":0,"term_taxonomy_id":749,"taxonomy":"post_tag","description":"","parent":0,"count":2,"filter":"raw","order":"0"},{"term_id":526,"name":"Klaus Billand","slug":"klaus-billand","term_group":0,"term_taxonomy_id":526,"taxonomy":"post_tag","description":"","parent":0,"count":8,"filter":"raw","order":"0"},{"term_id":751,"name":"Kompendium","slug":"kompendium","term_group":0,"term_taxonomy_id":751,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","order":"0"},{"term_id":757,"name":"Kurt Weill","slug":"kurt-weill","term_group":0,"term_taxonomy_id":757,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","order":"0"},{"term_id":487,"name":"Leo\u0161 Jan\u00e1\u010dek","slug":"leos-janacek","term_group":0,"term_taxonomy_id":487,"taxonomy":"post_tag","description":"","parent":0,"count":2,"filter":"raw","order":"0"},{"term_id":425,"name":"orpheus","slug":"orpheus","term_group":0,"term_taxonomy_id":425,"taxonomy":"post_tag","description":"","parent":0,"count":83,"filter":"raw","order":"0"},{"term_id":426,"name":"Orpheus Magazin","slug":"orpheus-magazin","term_group":0,"term_taxonomy_id":426,"taxonomy":"post_tag","description":"","parent":0,"count":83,"filter":"raw","order":"0"},{"term_id":750,"name":"Oswald Panagl","slug":"oswald-panagl","term_group":0,"term_taxonomy_id":750,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","order":"0"},{"term_id":50,"name":"Richard Strauss","slug":"richard-strauss","term_group":0,"term_taxonomy_id":50,"taxonomy":"post_tag","description":"","parent":0,"count":4,"filter":"raw","order":"0"},{"term_id":275,"name":"Walter Braunfels","slug":"walter-braunfels","term_group":0,"term_taxonomy_id":275,"taxonomy":"post_tag","description":"","parent":0,"count":2,"filter":"raw","order":"0"}]},"author_name":"Florian Maier","author_url":"https:\/\/www.orpheus-magazin.de\/de\/author\/redaktionorpheus-magazin-de\/","author_email":"redaktion@orpheus-magazin.de","author_website":"","author_description":"","author_facebook":"","author_twitter":"","author_instagram":"","author_role":["administrator"],"author_firstname":"Florian","author_lastname":"Maier","user_login":"redaktion@orpheus-magazin.de","author_avatar":"<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/5ee5bbfa3e4d8e8fd4c1781cc619164177d374083eb6aa532bc9f2ba5f9c346a?s=200&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/5ee5bbfa3e4d8e8fd4c1781cc619164177d374083eb6aa532bc9f2ba5f9c346a?s=400&#038;d=mm&#038;r=g 2x' class='avatar avatar-200 photo' height='200' width='200' decoding='async'\/>","author_avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5ee5bbfa3e4d8e8fd4c1781cc619164177d374083eb6aa532bc9f2ba5f9c346a?s=96&d=mm&r=g","comment_count":0,"post_likes":0,"post_views":0},"tpgb_post_category":{"category":"<a href=\"https:\/\/www.orpheus-magazin.de\/de\/category\/medien\/\" alt=\"Medien\"  class=\"category-medien\">Medien<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/category\/medien\/medien-2021-02\/\" alt=\"Medien 2021\/02\"  class=\"category-medien-2021-02\">Medien 2021\/02<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/category\/medien\/medien-2021-02\/medien-2021-02-buch\/\" alt=\"Medien 2021\/02 Buch\"  class=\"category-medien-2021-02-buch\">Medien 2021\/02 Buch<\/a> ","post_tag":"<a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/benjamin-britten\/\" alt=\"Benjamin Britten\"  class=\"post_tag-benjamin-britten\">Benjamin Britten<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/bohuslav-martinu\/\" alt=\"Bohuslav Martin\u016f\"  class=\"post_tag-bohuslav-martinu\">Bohuslav Martin\u016f<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/buchbesprechung\/\" alt=\"Buchbesprechung\"  class=\"post_tag-buchbesprechung\">Buchbesprechung<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/buchkritik\/\" alt=\"Buchkritik\"  class=\"post_tag-buchkritik\">Buchkritik<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/buchrezension\/\" alt=\"Buchrezension\"  class=\"post_tag-buchrezension\">Buchrezension<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/claude-debussy\/\" alt=\"Claude Debussy\"  class=\"post_tag-claude-debussy\">Claude Debussy<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/erich-wolfgang-korngold\/\" alt=\"Erich Wolfgang Korngold\"  class=\"post_tag-erich-wolfgang-korngold\">Erich Wolfgang Korngold<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/ferruccio-busoni\/\" alt=\"Ferruccio Busoni\"  class=\"post_tag-ferruccio-busoni\">Ferruccio Busoni<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/giacomo-puccini\/\" alt=\"Giacomo Puccini\"  class=\"post_tag-giacomo-puccini\">Giacomo Puccini<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/hans-pfitzner\/\" alt=\"Hans Pfitzner\"  class=\"post_tag-hans-pfitzner\">Hans Pfitzner<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/im-zeichen-der-moderne\/\" alt=\"Im Zeichen der Moderne\"  class=\"post_tag-im-zeichen-der-moderne\">Im Zeichen der Moderne<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/klassikbuch\/\" alt=\"Klassikbuch\"  class=\"post_tag-klassikbuch\">Klassikbuch<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/klaus-billand\/\" alt=\"Klaus Billand\"  class=\"post_tag-klaus-billand\">Klaus Billand<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/kompendium\/\" alt=\"Kompendium\"  class=\"post_tag-kompendium\">Kompendium<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/kurt-weill\/\" alt=\"Kurt Weill\"  class=\"post_tag-kurt-weill\">Kurt Weill<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/leos-janacek\/\" alt=\"Leo\u0161 Jan\u00e1\u010dek\"  class=\"post_tag-leos-janacek\">Leo\u0161 Jan\u00e1\u010dek<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/orpheus\/\" alt=\"orpheus\"  class=\"post_tag-orpheus\">orpheus<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/orpheus-magazin\/\" alt=\"Orpheus Magazin\"  class=\"post_tag-orpheus-magazin\">Orpheus Magazin<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/oswald-panagl\/\" alt=\"Oswald Panagl\"  class=\"post_tag-oswald-panagl\">Oswald Panagl<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/richard-strauss\/\" alt=\"Richard Strauss\"  class=\"post_tag-richard-strauss\">Richard Strauss<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/walter-braunfels\/\" alt=\"Walter Braunfels\"  class=\"post_tag-walter-braunfels\">Walter Braunfels<\/a> "},"_links":{"self":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/posts\/5241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/comments?post=5241"}],"version-history":[{"count":0,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/posts\/5241\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/media\/5216"}],"wp:attachment":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/media?parent=5241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/categories?post=5241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/tags?post=5241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}