{"id":5617,"date":"2021-04-13T17:35:04","date_gmt":"2021-04-13T15:35:04","guid":{"rendered":"https:\/\/www.orpheus-magazin.de\/?p=5617"},"modified":"2021-04-19T15:20:12","modified_gmt":"2021-04-19T13:20:12","slug":"operngondel-auf-kurssuche","status":"publish","type":"post","link":"https:\/\/www.orpheus-magazin.de\/de\/2021\/04\/13\/operngondel-auf-kurssuche\/","title":{"rendered":"Operngondel auf Kurssuche"},"content":{"rendered":"<p>Nach dem lauten Bl\u00e4tterrauschen rund um die Demission von Operndirektor Michael Fichtenholz soll sie im Idealfall f\u00fcr frische Schlagzeilen sorgen, die neue Produktion von \u201eLes contes d\u2019Hoffmann\u201c am Opernhaus Z\u00fcrich. Der ebenfalls in Bedr\u00e4ngnis geratene Haus-Chef Andreas Homoki bringt als Regisseur das Opus summum des K\u00f6lner Parisers heraus, nur elf Jahre nach der erfolgreichen letzten Z\u00fcrcher Premiere von Offenbachs einhundertzweiter (!) und letzter Oper. Nach dem Premierenstream folgen, Stand Redaktionsschluss, vier \u201eechte\u201c Vorstellungen im Mai. Er interessiere sich f\u00fcr den Spa\u00df in so vielen Situationen, die sich der ausgebuffte Theaterprofi Offenbach da wirkungsvoll erdacht habe, erkl\u00e4rt Homoki; der Faust\u2019sche Theaterdirektor h\u00e4tte sofort zugestimmt. Doch diese Spa\u00df-Situationen stehen dann zwei Akte lang so schablonenhaft verhandelt, lose und steif nebeneinander, dass die Nummernoper zur Revue wird. Der fehlt freilich die Showtreppe: Ein gro\u00dfes Fass und das erh\u00f6hte, zur ber\u00fchmten Barcarole unfehlbar schaukelnde B\u00fchnentrapez in der Mitte (Wolfgang Gussmann) sind karge B\u00fchnenbildkost und k\u00f6nnen eine stringente Entwicklung von Figuren und Plot nicht ersetzen. Auch die Kost\u00fcme strahlen jedenfalls am Bildschirm mehr Fundus aus denn Grand op\u00e9ra.<\/p>\n\n\n\n<p>Dass der Abend dann doch Fahrt aufnimmt, liegt nicht nur an der konzentrierter werdenden Personenf\u00fchrung, sondern haupts\u00e4chlich an den S\u00e4ngerinnen und S\u00e4ngern, angef\u00fchrt vom albanischen Tenor Saimir Pirgu, der Stimmreserven wie auch spielerischen Einsatz klug steigert und sein Hoffmann-Rollendeb\u00fct mit Strahlkraft und Selbstbewusstsein meistert. H\u00f6chst unterschiedlich und dabei s\u00e4mtlich beeindruckend: seine drei ungl\u00fccklichen Liebschaften. Die Amerikanerin Katrina Galka wirft sich bei ihrem Haus- und Rollendeb\u00fct als h\u00fcftsteife und h\u00f6hensichere Puppe Olympia furchtlos in die Koloraturen; mit sp\u00fcrbarer Lust am Spielen verleiht Lauren Fagan ihrer Kurtisane Giulietta eine robuste Verf\u00fchrungskraft, passgenau f\u00fcr den besoffenen Dichter; und die wunderbare Ekaterina Bakanova als Antonia (ein Clara-Schumann-Verschnitt am Fl\u00fcgel) bringt Schmelz in der Stimme und wohltuend atmende agogische Freiheit mit. In ihren Vierfachrollen setzen Andrew Foster-Williams mit Dapertuttos Spiegelarie und Spencer Lang als herrlich komischer Diener Frantz ihre Glanzlichter. Herausragend mit \u00fcber den ganzen Umfang samtigem und dabei stets strahlendem Mezzo und einer schauspielerischen Leistung, die alle anderen in den Schatten stellt: Alexandra Kadurina als Muse\/Nicklausse. Dirigent Antonio Fogliani f\u00fchrt sein S\u00e4ngerensemble per \u00dcbertragung aus dem Probenraum am Kreuzplatz sicher und formt ebendort einen erfrischend schlanken Orchesterklang, die Philharmonia Z\u00fcrich ist im Antonia-Akt am besten in Form (Holzbl\u00e4ser, Solo-Oboe!). Und Regisseur Homoki findet nach z\u00e4hem Anfang zu einem \u00fcberraschenden, aber sicher nicht zuf\u00e4lligen Ende: Die S\u00e4ngerin Stella begegnet dem K\u00fcnstlerkollegen Hoffmann und dem Machtmenschen Lindorf pl\u00f6tzlich selbstbestimmt und auf Augenh\u00f6he &#8230; Ein Opernhaus-Omen?<\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>Stephan Knies<\/em><\/p>\n\n\n\n<p><strong>\u201eLes contes d\u2019Hoffmann\u201c (\u201eHoffmanns Erz\u00e4hlungen\u201c) (1881) \/\/ Op\u00e9ra fantastique von Jacques Offenbach auf Basis der kritischen Edition von Michael Kaye und Jean-Christophe Keck<\/strong><\/p>\n\n\n\n<p><a href=\"https:\/\/www.opernhaus.ch\/spielplan\/kalendarium\/les-contes-d-hoffmann\/2020-2021\/\" target=\"_blank\" aria-label=\"Die Inszenierung ist als Video-on-Demand bis Ende April kostenfrei \u00fcber die Website des Theaters abrufbar. (opens in a new tab)\" rel=\"noreferrer noopener\" class=\"ek-link\">Die Inszenierung ist als Video-on-Demand bis Ende April kostenfrei \u00fcber die Website des Theaters abrufbar.<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p><span class=\"location\">Z\u00fcrich \/ Opernhaus Z\u00fcrich (April 2021)<\/span><\/br><br \/>\nBilder von der Stange und tolle Stimmen in \u201eLes contes d\u2019Hoffmann\u201c<\/p>","protected":false},"author":12,"featured_media":5618,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"tpgb_global_settings":"","_editorskit_title_hidden":false,"_editorskit_reading_time":2,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_eb_attr":"","footnotes":""},"categories":[34,815],"tags":[1096,1088,1094,1097,1093,1086,419,1100,1091,1092,418,1087,1099,480,422,256,423,450,425,426,1098,424,1101,1090,1095,777,481,994,1089,1085],"class_list":["post-5617","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rezensionen","category-rezensionen-2021-03","tag-alexandra-kadurina","tag-andreas-homoki","tag-andrew-foster-williams","tag-antonio-fogliani","tag-ekaterina-bakanova","tag-hoffmanns-erzaehlungen","tag-jacques-offenbach","tag-jean-christophe-keck","tag-katrina-galka","tag-lauren-fagan","tag-les-contes-dhoffmann","tag-michael-fichtenholz","tag-michael-kaye","tag-musiktheater","tag-oper","tag-opernhaus-zuerich","tag-opernkritik","tag-opernstreaming","tag-orpheus","tag-orpheus-magazin","tag-philharmonia-zuerich","tag-premierenkritik","tag-premierenstreaming","tag-saimir-pirgu","tag-spencer-lang","tag-stephan-knies","tag-streamingkritik","tag-streamingpremiere","tag-wolfgang-gussmann","tag-zuerich"],"tpgb_featured_images":{"full":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2021\/04\/FSG_Zuerich_Les-contes-dHoffmann-les_contes_dhoffmann_c_monika_rittershaus_135-scaled.jpg",2560,2134,false],"tp-image-grid":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2021\/04\/FSG_Zuerich_Les-contes-dHoffmann-les_contes_dhoffmann_c_monika_rittershaus_135-scaled.jpg",700,584,false],"thumbnail":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2021\/04\/FSG_Zuerich_Les-contes-dHoffmann-les_contes_dhoffmann_c_monika_rittershaus_135-scaled-e1618327931129-150x150.jpg",150,150,true],"medium":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2021\/04\/FSG_Zuerich_Les-contes-dHoffmann-les_contes_dhoffmann_c_monika_rittershaus_135-scaled-e1618327931129-300x169.jpg",300,169,true],"medium_large":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2021\/04\/FSG_Zuerich_Les-contes-dHoffmann-les_contes_dhoffmann_c_monika_rittershaus_135-scaled-e1618327931129-768x433.jpg",600,338,true],"large":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2021\/04\/FSG_Zuerich_Les-contes-dHoffmann-les_contes_dhoffmann_c_monika_rittershaus_135-scaled-e1618327931129-1024x577.jpg",600,338,true],"default":"https:\/\/www.orpheus-magazin.de\/wp-content\/plugins\/the-plus-addons-for-block-editor\/assets\/images\/tpgb-placeholder.jpg"},"tpgb_post_meta_info":{"get_date":"13. April 2021","get_modified_date":"19. April 2021","category_list":{"category":[{"term_id":34,"name":"Rezensionen","slug":"rezensionen","term_group":0,"term_taxonomy_id":34,"taxonomy":"category","description":"","parent":0,"count":507,"filter":"raw","order":"0"},{"term_id":815,"name":"Rezensionen 2021\/03","slug":"rezensionen-2021-03","term_group":0,"term_taxonomy_id":815,"taxonomy":"category","description":"","parent":34,"count":21,"filter":"raw","order":"0"}],"post_tag":[{"term_id":1096,"name":"Alexandra Kadurina","slug":"alexandra-kadurina","term_group":0,"term_taxonomy_id":1096,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","order":"0"},{"term_id":1088,"name":"Andreas Homoki","slug":"andreas-homoki","term_group":0,"term_taxonomy_id":1088,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","order":"0"},{"term_id":1094,"name":"Andrew Foster-Williams","slug":"andrew-foster-williams","term_group":0,"term_taxonomy_id":1094,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","order":"0"},{"term_id":1097,"name":"Antonio Fogliani","slug":"antonio-fogliani","term_group":0,"term_taxonomy_id":1097,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","order":"0"},{"term_id":1093,"name":"Ekaterina Bakanova","slug":"ekaterina-bakanova","term_group":0,"term_taxonomy_id":1093,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","order":"0"},{"term_id":1086,"name":"Hoffmanns Erz\u00e4hlungen","slug":"hoffmanns-erzaehlungen","term_group":0,"term_taxonomy_id":1086,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","order":"0"},{"term_id":419,"name":"Jacques Offenbach","slug":"jacques-offenbach","term_group":0,"term_taxonomy_id":419,"taxonomy":"post_tag","description":"","parent":0,"count":2,"filter":"raw","order":"0"},{"term_id":1100,"name":"Jean-Christophe Keck","slug":"jean-christophe-keck","term_group":0,"term_taxonomy_id":1100,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","order":"0"},{"term_id":1091,"name":"Katrina Galka","slug":"katrina-galka","term_group":0,"term_taxonomy_id":1091,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","order":"0"},{"term_id":1092,"name":"Lauren Fagan","slug":"lauren-fagan","term_group":0,"term_taxonomy_id":1092,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","order":"0"},{"term_id":418,"name":"Les contes d\u2019Hoffmann","slug":"les-contes-dhoffmann","term_group":0,"term_taxonomy_id":418,"taxonomy":"post_tag","description":"","parent":0,"count":2,"filter":"raw","order":"0"},{"term_id":1087,"name":"Michael Fichtenholz","slug":"michael-fichtenholz","term_group":0,"term_taxonomy_id":1087,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","order":"0"},{"term_id":1099,"name":"Michael Kaye","slug":"michael-kaye","term_group":0,"term_taxonomy_id":1099,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","order":"0"},{"term_id":480,"name":"Musiktheater","slug":"musiktheater","term_group":0,"term_taxonomy_id":480,"taxonomy":"post_tag","description":"","parent":0,"count":45,"filter":"raw","order":"0"},{"term_id":422,"name":"Oper","slug":"oper","term_group":0,"term_taxonomy_id":422,"taxonomy":"post_tag","description":"","parent":0,"count":43,"filter":"raw","order":"0"},{"term_id":256,"name":"Opernhaus Z\u00fcrich","slug":"opernhaus-zuerich","term_group":0,"term_taxonomy_id":256,"taxonomy":"post_tag","description":"","parent":0,"count":2,"filter":"raw","order":"0"},{"term_id":423,"name":"Opernkritik","slug":"opernkritik","term_group":0,"term_taxonomy_id":423,"taxonomy":"post_tag","description":"","parent":0,"count":42,"filter":"raw","order":"0"},{"term_id":450,"name":"Opernstreaming","slug":"opernstreaming","term_group":0,"term_taxonomy_id":450,"taxonomy":"post_tag","description":"","parent":0,"count":28,"filter":"raw","order":"0"},{"term_id":425,"name":"orpheus","slug":"orpheus","term_group":0,"term_taxonomy_id":425,"taxonomy":"post_tag","description":"","parent":0,"count":83,"filter":"raw","order":"0"},{"term_id":426,"name":"Orpheus Magazin","slug":"orpheus-magazin","term_group":0,"term_taxonomy_id":426,"taxonomy":"post_tag","description":"","parent":0,"count":83,"filter":"raw","order":"0"},{"term_id":1098,"name":"Philharmonia Z\u00fcrich","slug":"philharmonia-zuerich","term_group":0,"term_taxonomy_id":1098,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","order":"0"},{"term_id":424,"name":"Premierenkritik","slug":"premierenkritik","term_group":0,"term_taxonomy_id":424,"taxonomy":"post_tag","description":"","parent":0,"count":56,"filter":"raw","order":"0"},{"term_id":1101,"name":"Premierenstreaming","slug":"premierenstreaming","term_group":0,"term_taxonomy_id":1101,"taxonomy":"post_tag","description":"","parent":0,"count":11,"filter":"raw","order":"0"},{"term_id":1090,"name":"Saimir Pirgu","slug":"saimir-pirgu","term_group":0,"term_taxonomy_id":1090,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","order":"0"},{"term_id":1095,"name":"Spencer Lang","slug":"spencer-lang","term_group":0,"term_taxonomy_id":1095,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","order":"0"},{"term_id":777,"name":"Stephan Knies","slug":"stephan-knies","term_group":0,"term_taxonomy_id":777,"taxonomy":"post_tag","description":"","parent":0,"count":2,"filter":"raw","order":"0"},{"term_id":481,"name":"Streamingkritik","slug":"streamingkritik","term_group":0,"term_taxonomy_id":481,"taxonomy":"post_tag","description":"","parent":0,"count":33,"filter":"raw","order":"0"},{"term_id":994,"name":"Streamingpremiere","slug":"streamingpremiere","term_group":0,"term_taxonomy_id":994,"taxonomy":"post_tag","description":"","parent":0,"count":13,"filter":"raw","order":"0"},{"term_id":1089,"name":"Wolfgang Gussmann","slug":"wolfgang-gussmann","term_group":0,"term_taxonomy_id":1089,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","order":"0"},{"term_id":1085,"name":"Z\u00fcrich","slug":"zuerich","term_group":0,"term_taxonomy_id":1085,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","order":"0"}]},"author_name":"Florian Maier","author_url":"https:\/\/www.orpheus-magazin.de\/de\/author\/redaktionorpheus-magazin-de\/","author_email":"redaktion@orpheus-magazin.de","author_website":"","author_description":"","author_facebook":"","author_twitter":"","author_instagram":"","author_role":["administrator"],"author_firstname":"Florian","author_lastname":"Maier","user_login":"redaktion@orpheus-magazin.de","author_avatar":"<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/5ee5bbfa3e4d8e8fd4c1781cc619164177d374083eb6aa532bc9f2ba5f9c346a?s=200&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/5ee5bbfa3e4d8e8fd4c1781cc619164177d374083eb6aa532bc9f2ba5f9c346a?s=400&#038;d=mm&#038;r=g 2x' class='avatar avatar-200 photo' height='200' width='200' decoding='async'\/>","author_avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5ee5bbfa3e4d8e8fd4c1781cc619164177d374083eb6aa532bc9f2ba5f9c346a?s=96&d=mm&r=g","comment_count":0,"post_likes":0,"post_views":0},"tpgb_post_category":{"category":"<a href=\"https:\/\/www.orpheus-magazin.de\/de\/category\/rezensionen\/\" alt=\"Rezensionen\"  class=\"category-rezensionen\">Rezensionen<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/category\/rezensionen\/rezensionen-2021-03\/\" alt=\"Rezensionen 2021\/03\"  class=\"category-rezensionen-2021-03\">Rezensionen 2021\/03<\/a> ","post_tag":"<a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/alexandra-kadurina\/\" alt=\"Alexandra Kadurina\"  class=\"post_tag-alexandra-kadurina\">Alexandra Kadurina<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/andreas-homoki\/\" alt=\"Andreas Homoki\"  class=\"post_tag-andreas-homoki\">Andreas Homoki<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/andrew-foster-williams\/\" alt=\"Andrew Foster-Williams\"  class=\"post_tag-andrew-foster-williams\">Andrew Foster-Williams<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/antonio-fogliani\/\" alt=\"Antonio Fogliani\"  class=\"post_tag-antonio-fogliani\">Antonio Fogliani<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/ekaterina-bakanova\/\" alt=\"Ekaterina Bakanova\"  class=\"post_tag-ekaterina-bakanova\">Ekaterina Bakanova<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/hoffmanns-erzaehlungen\/\" alt=\"Hoffmanns Erz\u00e4hlungen\"  class=\"post_tag-hoffmanns-erzaehlungen\">Hoffmanns Erz\u00e4hlungen<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/jacques-offenbach\/\" alt=\"Jacques Offenbach\"  class=\"post_tag-jacques-offenbach\">Jacques Offenbach<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/jean-christophe-keck\/\" alt=\"Jean-Christophe Keck\"  class=\"post_tag-jean-christophe-keck\">Jean-Christophe Keck<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/katrina-galka\/\" alt=\"Katrina Galka\"  class=\"post_tag-katrina-galka\">Katrina Galka<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/lauren-fagan\/\" alt=\"Lauren Fagan\"  class=\"post_tag-lauren-fagan\">Lauren Fagan<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/les-contes-dhoffmann\/\" alt=\"Les contes d\u2019Hoffmann\"  class=\"post_tag-les-contes-dhoffmann\">Les contes d\u2019Hoffmann<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/michael-fichtenholz\/\" alt=\"Michael Fichtenholz\"  class=\"post_tag-michael-fichtenholz\">Michael Fichtenholz<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/michael-kaye\/\" alt=\"Michael Kaye\"  class=\"post_tag-michael-kaye\">Michael Kaye<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/musiktheater\/\" alt=\"Musiktheater\"  class=\"post_tag-musiktheater\">Musiktheater<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/oper\/\" alt=\"Oper\"  class=\"post_tag-oper\">Oper<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/opernhaus-zuerich\/\" alt=\"Opernhaus Z\u00fcrich\"  class=\"post_tag-opernhaus-zuerich\">Opernhaus Z\u00fcrich<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/opernkritik\/\" alt=\"Opernkritik\"  class=\"post_tag-opernkritik\">Opernkritik<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/opernstreaming\/\" alt=\"Opernstreaming\"  class=\"post_tag-opernstreaming\">Opernstreaming<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/orpheus\/\" alt=\"orpheus\"  class=\"post_tag-orpheus\">orpheus<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/orpheus-magazin\/\" alt=\"Orpheus Magazin\"  class=\"post_tag-orpheus-magazin\">Orpheus Magazin<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/philharmonia-zuerich\/\" alt=\"Philharmonia Z\u00fcrich\"  class=\"post_tag-philharmonia-zuerich\">Philharmonia Z\u00fcrich<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/premierenkritik\/\" alt=\"Premierenkritik\"  class=\"post_tag-premierenkritik\">Premierenkritik<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/premierenstreaming\/\" alt=\"Premierenstreaming\"  class=\"post_tag-premierenstreaming\">Premierenstreaming<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/saimir-pirgu\/\" alt=\"Saimir Pirgu\"  class=\"post_tag-saimir-pirgu\">Saimir Pirgu<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/spencer-lang\/\" alt=\"Spencer Lang\"  class=\"post_tag-spencer-lang\">Spencer Lang<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/stephan-knies\/\" alt=\"Stephan Knies\"  class=\"post_tag-stephan-knies\">Stephan Knies<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/streamingkritik\/\" alt=\"Streamingkritik\"  class=\"post_tag-streamingkritik\">Streamingkritik<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/streamingpremiere\/\" alt=\"Streamingpremiere\"  class=\"post_tag-streamingpremiere\">Streamingpremiere<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/wolfgang-gussmann\/\" alt=\"Wolfgang Gussmann\"  class=\"post_tag-wolfgang-gussmann\">Wolfgang Gussmann<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/tag\/zuerich\/\" alt=\"Z\u00fcrich\"  class=\"post_tag-zuerich\">Z\u00fcrich<\/a> "},"_links":{"self":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/posts\/5617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/comments?post=5617"}],"version-history":[{"count":0,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/posts\/5617\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/media\/5618"}],"wp:attachment":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/media?parent=5617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/categories?post=5617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/tags?post=5617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}