{"id":9290,"date":"2023-09-22T21:29:00","date_gmt":"2023-09-22T19:29:00","guid":{"rendered":"https:\/\/www.orpheus-magazin.de\/?p=9290"},"modified":"2023-10-24T21:29:49","modified_gmt":"2023-10-24T19:29:49","slug":"wien-pandora","status":"publish","type":"post","link":"https:\/\/www.orpheus-magazin.de\/de\/2023\/09\/22\/wien-pandora\/","title":{"rendered":"Out of the box"},"content":{"rendered":"<p>Jenseits der Tempel der klassischen Musik haben sich die Musiktheatertage Wien als kleines, aber hochengagiertes Festival etabliert. Thomas Cornelius Desi und Georg Steker sind als k\u00fcnstlerische Leiter Jahr um Jahr bem\u00fcht, ein m\u00f6glichst abwechslungsreiches Programm auf die Beine zu stellen. Das Ziel: ausgetretene Pfade zu verlassen, m\u00f6glichst viele Musikstile zu vereinen, neue Medien, Technologien und Formate zu integrieren, junge K\u00fcnstlerinnen und K\u00fcnstler zu f\u00f6rdern und Kompositionsauftr\u00e4ge zu vergeben.<\/p>\n\n\n\n<p>Das Auftaktst\u00fcck des diesj\u00e4hrigen Festivals \u201eHeiliger Zorn\/detuned\u201c aus der Feder von Komponist und Regisseur Thomas Cornelius Desi in der Wiener Hofburgkapelle verursacht in den K\u00f6pfen der Zuschauer allerdings eher Verwirrung als Entz\u00fcckung. Das Thema rund um den historischen Konflikt zwischen dem zornigen K\u00f6nig Henry II Plantagenet und seinem gelassenen Kanzler Thomas Becket z\u00fcndet nicht. Die Idee, den Jugendchor aus Sch\u00fclerinnen und Sch\u00fclern des AkG Beethovenplatz in das St\u00fcck miteinzubeziehen, ist lobenswert. Allerdings rufen die Tableaus, zu denen sich die Jugendlichen mit Hilfe altmodischer Requisiten formieren m\u00fcssen, nur bei anwesenden Familienangeh\u00f6rigen wohlwollende Begeisterung hervor.<\/p>\n\n\n\n<p>Ganz anders pr\u00e4sentiert sich die Urauff\u00fchrung der frisch komponierten Oper von Matthias Kranebitter, \u201ePandora\u201c. Bekanntlich verhei\u00dft es nichts Gutes, die B\u00fcchse der von Hephaistos aus Lehm geschaffenen Frau zu \u00f6ffnen. Hier erw\u00e4chst daraus Kreatives, ein finessenreicher Mix aus Performance, exzellentem Gesang, gro\u00dfer Darstellungskunst, noch gr\u00f6\u00dferem Durchhalteverm\u00f6gen der K\u00fcnstlerinnen und K\u00fcnstler, einem spannenden B\u00fchnenbild und abwechslungsreicher Musik. Der 1980 geborene Wiener Komponist sammelte Erfahrungen in zahlreichen Musikstilen, mit diversen Orchestern und Klangformationen, die sich mit der sogenannten modernen Musik auseinandersetzen.<\/p>\n\n\n\n<p>Diesmal belebt er den barocken Operntorso \u201ePandora\u201c nach verschollener Musik von Joseph-Niclas-Pancrace Royer und Worten von Voltaire wieder. Da dreht sich alles um Freiheit, Revolution, Guillotinen und Cembali. Als Zuseher braucht man schon Zeit, um sich zwischen den gro\u00dfen wei\u00dfen Boxen, den in grau-wei\u00dfe stilisierte Krinolinen verpackten S\u00e4ngern zu orientieren, die Erweckung der Pandora zu identifizieren und die Folgen der \u00d6ffnung der ber\u00fchmten B\u00fcchse zu verstehen. Aber alles kommt sehr witzig daher, die Musik ist gef\u00e4llig, sie dekonstruiert gekonnt barockes Notenmaterial in das 21. Jahrhundert, alles passend zum sanft br\u00f6ckelnden Ambiente des Odeon Theaters.<\/p>\n\n\n\n<p>Regisseur Michael H\u00f6ppner beweist Humor mit der Installation eines Roboterarms statt eines Dirigenten, Vinicius Katta darf nach wenigen Minuten allerdings das Black Page Orchestra pers\u00f6nlich leiten. Szenograf Christopher Sturmer greift tief in Farbtiegel und Lehmk\u00fcbel, um die S\u00e4nger zu Kunstobjekten zu verpacken. Georg Bochow (Countertenor), Heike Porstein (Sopran) und Andreas Jankowitsch (Bariton) sind nicht nur f\u00fcr ihre ausgezeichneten s\u00e4ngerischen Leistungen lobend zu erw\u00e4hnen, sondern auch f\u00fcr die gro\u00dfe Ernsthaftigkeit, mit der sie ihre Figuren im besten Licht erscheinen lassen. Vielleicht nicht der gr\u00f6\u00dfte Abend, den man als Zuschauer erleben kann, aber ein sehr interessanter.<\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>Susanne Dressler<\/em><\/p>\n\n\n\n<p><strong>\u201ePandora\u201c (2023) \/\/ Eine Cyber-Reanimation des barocken Operntorsos von Royer und Voltaire durch Matthias Kranebitter<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p><span class=\"location\">Wien \/ Musiktheatertage Wien (September 2023)<\/span><\/br><br \/>\n\u201ePandora\u201c: \u201eCyber-Reanimation\u201c eines barocken Operntorsos<\/p>","protected":false},"author":12,"featured_media":9291,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"tpgb_global_settings":"","_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_eb_attr":"","footnotes":""},"categories":[34,1687],"tags":[],"class_list":["post-9290","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rezensionen","category-rezensionen-2023-06"],"tpgb_featured_images":{"full":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2023\/10\/Musiktheatertage-Wien_Pandora-c-Nick-Mangafas.jpg",1500,844,false],"tp-image-grid":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2023\/10\/Musiktheatertage-Wien_Pandora-c-Nick-Mangafas.jpg",700,394,false],"thumbnail":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2023\/10\/Musiktheatertage-Wien_Pandora-c-Nick-Mangafas-150x150.jpg",150,150,true],"medium":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2023\/10\/Musiktheatertage-Wien_Pandora-c-Nick-Mangafas-300x169.jpg",300,169,true],"medium_large":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2023\/10\/Musiktheatertage-Wien_Pandora-c-Nick-Mangafas-768x432.jpg",600,338,true],"large":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2023\/10\/Musiktheatertage-Wien_Pandora-c-Nick-Mangafas-1024x576.jpg",600,338,true],"default":"https:\/\/www.orpheus-magazin.de\/wp-content\/plugins\/the-plus-addons-for-block-editor\/assets\/images\/tpgb-placeholder.jpg"},"tpgb_post_meta_info":{"get_date":"22. September 2023","get_modified_date":"24. Oktober 2023","category_list":{"category":[{"term_id":34,"name":"Rezensionen","slug":"rezensionen","term_group":0,"term_taxonomy_id":34,"taxonomy":"category","description":"","parent":0,"count":507,"filter":"raw","order":"0"},{"term_id":1687,"name":"Rezensionen 2023\/06","slug":"rezensionen-2023-06","term_group":0,"term_taxonomy_id":1687,"taxonomy":"category","description":"","parent":34,"count":14,"filter":"raw","order":"0"}],"post_tag":false},"author_name":"Florian Maier","author_url":"https:\/\/www.orpheus-magazin.de\/de\/author\/redaktionorpheus-magazin-de\/","author_email":"redaktion@orpheus-magazin.de","author_website":"","author_description":"","author_facebook":"","author_twitter":"","author_instagram":"","author_role":["administrator"],"author_firstname":"Florian","author_lastname":"Maier","user_login":"redaktion@orpheus-magazin.de","author_avatar":"<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/5ee5bbfa3e4d8e8fd4c1781cc619164177d374083eb6aa532bc9f2ba5f9c346a?s=200&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/5ee5bbfa3e4d8e8fd4c1781cc619164177d374083eb6aa532bc9f2ba5f9c346a?s=400&#038;d=mm&#038;r=g 2x' class='avatar avatar-200 photo' height='200' width='200' decoding='async'\/>","author_avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5ee5bbfa3e4d8e8fd4c1781cc619164177d374083eb6aa532bc9f2ba5f9c346a?s=96&d=mm&r=g","comment_count":0,"post_likes":0,"post_views":0},"tpgb_post_category":{"category":"<a href=\"https:\/\/www.orpheus-magazin.de\/de\/category\/rezensionen\/\" alt=\"Rezensionen\"  class=\"category-rezensionen\">Rezensionen<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/category\/rezensionen\/rezensionen-2023-06\/\" alt=\"Rezensionen 2023\/06\"  class=\"category-rezensionen-2023-06\">Rezensionen 2023\/06<\/a> "},"_links":{"self":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/posts\/9290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/comments?post=9290"}],"version-history":[{"count":0,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/posts\/9290\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/media\/9291"}],"wp:attachment":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/media?parent=9290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/categories?post=9290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/tags?post=9290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}