{"id":9621,"date":"2024-02-07T13:48:34","date_gmt":"2024-02-07T12:48:34","guid":{"rendered":"https:\/\/www.orpheus-magazin.de\/?p=9621"},"modified":"2024-02-29T13:49:37","modified_gmt":"2024-02-29T12:49:37","slug":"berlin-rusalka","status":"publish","type":"post","link":"https:\/\/www.orpheus-magazin.de\/de\/2024\/02\/07\/berlin-rusalka\/","title":{"rendered":"Gregor Samsas kleine Schwester"},"content":{"rendered":"<p>Korn\u00e9l Mundrucz\u00f3s Neuinszenierung der \u201eRusalka\u201c pr\u00e4sentiert gleich zwei Deutungen des Stoffes: eine reale und eine surreale. Zun\u00e4chst zeigt der Regisseur im B\u00fchnenbild von Monika Pormale eine an sozialen Gegens\u00e4tzen scheiternde Liebesgeschichte. Dvo\u0159\u00e1ks Seejungfrau erscheint als Teenager, der mit drei Mitbewohnerinnen (\u201eElfen\u201c) und einem verlotterten Alt-68er (\u201eWassermann\u201c) in einer sch\u00e4bigen Prekariats-Etagenwohnung haust. Sie ist ungl\u00fccklich in den wohlhabenden Mieter (\u201ePrinz\u201c) aus dem oberen Stockwerk verliebt. In ihrem Liebeskummer verkriecht sie sich in die Badewanne. Um Rusalka f\u00fcr ihren M\u00e4rchenprinzen aufzuh\u00fcbschen, verpasst ihr die Nachbarin (die \u201eHexe\u201c Je\u017eibaba) einen Haarschnitt und ein schickes Kleid. Das ist plausibel. Unplausibel ist, dass dazu unter Einsatz von Trockeneisnebel ein Zaubertrank gebraut werden muss und sie dadurch sprachlos wird. Im zweiten Akt geht es statt an den Hof des Prinzen einfach ein Stockwerk h\u00f6her in eine stylische Penthouse-Wohnung. Die hochn\u00e4sige Familie des Br\u00e4utigams mobbt dort das Unterschichtm\u00e4dchen. Der Wassermann holt die Gescheiterte zur\u00fcck in die Etagenwohnung. Damit k\u00f6nnte die Geschichte abgeschlossen sein.<\/p>\n\n\n\n<p>Der letzte Akt pr\u00e4sentiert eine \u00fcberraschend neue Deutung: Rusalka ist statt zum \u201eIrrlicht\u201c zu einem riesigen, schwarzen, gliederf\u00fc\u00dferartigen Insekt mutiert. Das B\u00fchnenbild wechselt erneut die Etage, nun nach unten in den Keller. Elfen und Wassermann treten dort als verunstaltete Mutanten auf. Die Insekten-Rusalka schl\u00e4ngelt sich \u00fcber den Boden und versetzt dem ihr gefolgten Prinzen t\u00f6dliche K\u00fcsse. So geht durch die Inszenierung ein Bruch. Denn die aus Franz Kafkas \u201eVerwandlung\u201c entlehnte Insekten-Metapher des existentiellen Fremdseins ist nicht deckungsgleich mit dem zun\u00e4chst gezeigten Fremdsein des Prekariats-M\u00e4dchens in einer Oberschichten-Welt. Dabei harmoniert die Pr\u00e4sentation der Nixe als kleine Schwester von Gregor Samsa in ihrer Phantastik mit dem Stoff sogar besser als das Herunterbrechen des M\u00e4rchens auf eine sozialkritisch aufgepolsterte Liebesgeschichte. Nicht zuletzt erz\u00e4hlt die Partitur, die Robin Ticciati mit der Staatskapelle Berlin farbig und atmosph\u00e4risch umsetzt, von einer verzauberten Welt, die in den ersten beiden Akten auf der B\u00fchne nicht gezeigt wird.<\/p>\n\n\n\n<p>Christiane Karg in der Titelpartie beglaubigt beide Regieans\u00e4tze mit intensivem Spiel. Als zur Stummheit verdammte Au\u00dfenseiterin \u00fcberzeugt sie im zweiten Akt sogar t\u00e4nzerisch (Choreografie: Canda\u015f Ba\u015f). Nach einem ausbuchstabiert klingenden \u201eLied an den Mond\u201c findet sie intensive T\u00f6ne f\u00fcr die zunehmende Verzweiflung ihrer Figur. Gro\u00dfartig gestaltet Mika Kares mit profundem Bass den Wassermann, saftige Mezzot\u00f6ne hat Anna Kissjudit f\u00fcr die Je\u017eibaba parat. Pavel \u010cernoch bietet f\u00fcr den Prinzen solides Tenormaterial auf. Die \u201eFremde F\u00fcrstin\u201c der Anna Samuil wirkt dagegen zu hell timbriert und irritiert mit einigen schrillen T\u00f6nen in der H\u00f6he. Die kleineren Partien sind s\u00e4mtlich rollendeckend besetzt. Am Ende bleibt der Eindruck von einer musikalisch ordentlichen Auff\u00fchrung mit disparaten Regieideen.<\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>Dr. Michael Demel<\/em><\/p>\n\n\n\n<p><strong>\u201eRusalka\u201c (1901) \/\/ Lyrisches M\u00e4rchen von Anton\u00edn Dvo\u0159\u00e1k<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p><span class=\"location\">Berlin \/ Staatsoper Unter den Linden (Februar 2024)<\/span><\/br><br \/>\nDvo\u0159\u00e1ks \u201eRusalka\u201c in zwei Varianten<\/p>","protected":false},"author":12,"featured_media":9622,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"tpgb_global_settings":"","_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_eb_attr":"","footnotes":""},"categories":[34,1691],"tags":[],"class_list":["post-9621","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rezensionen","category-rezensionen-2024-02"],"tpgb_featured_images":{"full":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2024\/02\/Staatsoper-Unter-den-Linden_Rusalka-c-Gianmarco-Bresadola.jpg",1500,844,false],"tp-image-grid":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2024\/02\/Staatsoper-Unter-den-Linden_Rusalka-c-Gianmarco-Bresadola.jpg",700,394,false],"thumbnail":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2024\/02\/Staatsoper-Unter-den-Linden_Rusalka-c-Gianmarco-Bresadola-150x150.jpg",150,150,true],"medium":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2024\/02\/Staatsoper-Unter-den-Linden_Rusalka-c-Gianmarco-Bresadola-300x169.jpg",300,169,true],"medium_large":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2024\/02\/Staatsoper-Unter-den-Linden_Rusalka-c-Gianmarco-Bresadola-768x432.jpg",600,338,true],"large":["https:\/\/www.orpheus-magazin.de\/wp-content\/uploads\/2024\/02\/Staatsoper-Unter-den-Linden_Rusalka-c-Gianmarco-Bresadola-1024x576.jpg",600,338,true],"default":"https:\/\/www.orpheus-magazin.de\/wp-content\/plugins\/the-plus-addons-for-block-editor\/assets\/images\/tpgb-placeholder.jpg"},"tpgb_post_meta_info":{"get_date":"7. Februar 2024","get_modified_date":"29. Februar 2024","category_list":{"category":[{"term_id":34,"name":"Rezensionen","slug":"rezensionen","term_group":0,"term_taxonomy_id":34,"taxonomy":"category","description":"","parent":0,"count":507,"filter":"raw","order":"0"},{"term_id":1691,"name":"Rezensionen 2024\/02","slug":"rezensionen-2024-02","term_group":0,"term_taxonomy_id":1691,"taxonomy":"category","description":"","parent":34,"count":10,"filter":"raw","order":"0"}],"post_tag":false},"author_name":"Florian Maier","author_url":"https:\/\/www.orpheus-magazin.de\/de\/author\/redaktionorpheus-magazin-de\/","author_email":"redaktion@orpheus-magazin.de","author_website":"","author_description":"","author_facebook":"","author_twitter":"","author_instagram":"","author_role":["administrator"],"author_firstname":"Florian","author_lastname":"Maier","user_login":"redaktion@orpheus-magazin.de","author_avatar":"<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/5ee5bbfa3e4d8e8fd4c1781cc619164177d374083eb6aa532bc9f2ba5f9c346a?s=200&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/5ee5bbfa3e4d8e8fd4c1781cc619164177d374083eb6aa532bc9f2ba5f9c346a?s=400&#038;d=mm&#038;r=g 2x' class='avatar avatar-200 photo' height='200' width='200' decoding='async'\/>","author_avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5ee5bbfa3e4d8e8fd4c1781cc619164177d374083eb6aa532bc9f2ba5f9c346a?s=96&d=mm&r=g","comment_count":0,"post_likes":0,"post_views":0},"tpgb_post_category":{"category":"<a href=\"https:\/\/www.orpheus-magazin.de\/de\/category\/rezensionen\/\" alt=\"Rezensionen\"  class=\"category-rezensionen\">Rezensionen<\/a> <a href=\"https:\/\/www.orpheus-magazin.de\/de\/category\/rezensionen\/rezensionen-2024-02\/\" alt=\"Rezensionen 2024\/02\"  class=\"category-rezensionen-2024-02\">Rezensionen 2024\/02<\/a> "},"_links":{"self":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/posts\/9621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/comments?post=9621"}],"version-history":[{"count":0,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/posts\/9621\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/media\/9622"}],"wp:attachment":[{"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/media?parent=9621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/categories?post=9621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.orpheus-magazin.de\/de\/wp-json\/wp\/v2\/tags?post=9621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}